{"id":2154,"date":"2025-03-02T16:36:56","date_gmt":"2025-03-02T08:36:56","guid":{"rendered":"https:\/\/led.amasly.com\/?p=2154"},"modified":"2025-03-06T23:04:38","modified_gmt":"2025-03-06T15:04:38","slug":"coal-mine-explosion-proof-inspection-standards","status":"publish","type":"post","link":"https:\/\/led.amasly.com\/pt\/explosion-proof-equipment\/coal-mine-explosion-proof-inspection-standards\/","title":{"rendered":"Normas de inspe\u00e7\u00e3o \u00e0 prova de explos\u00e3o de minas de carv\u00e3o"},"content":{"rendered":"<h1 class=\"wp-block-heading has-text-align-center\"><strong>Normas de inspe\u00e7\u00e3o \u00e0 prova de explos\u00e3o em minas de carv\u00e3o<\/strong><strong><\/strong><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>I. Disposi\u00e7\u00f5es gerais:<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>&nbsp; &nbsp; 1. A fim de continuar a aplicar os \u201cRegulamentos de Seguran\u00e7a das Minas de Carv\u00e3o\u201d e as normas e regulamentos relativos \u00e0 eletricidade \u00e0 prova de explos\u00e3o, melhorar a compreens\u00e3o dos trabalhadores electromec\u00e2nicos sobre o desempenho da eletricidade \u00e0 prova de explos\u00e3o e facilitar o dom\u00ednio da utiliza\u00e7\u00e3o das normas no trabalho pr\u00e1tico, de modo a refor\u00e7ar a gest\u00e3o cient\u00edfica da eletricidade \u00e0 prova de explos\u00e3o nas minas de carv\u00e3o subterr\u00e2neas, melhorar a qualidade da manuten\u00e7\u00e3o, eliminar as falhas el\u00e9ctricas e realizar o funcionamento seguro dos equipamentos el\u00e9ctricos, s\u00e3o formuladas as \u201cRegras\u201d.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 2. Todo o equipamento el\u00e9trico subterr\u00e2neo (incluindo o pequeno equipamento el\u00e9trico) deve ser selecionado em conformidade com os requisitos dos artigos 444\u00ba e 7\u00ba dos regulamentos relativos \u00e0 seguran\u00e7a das minas de carv\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 3. Os inspectores \u00e0 prova de explos\u00e3o a tempo inteiro devem ser formados e examinados pelas autoridades superiores e obter um certificado de compet\u00eancia. Os inspectores \u00e0 prova de explos\u00e3o a tempo parcial devem ser submetidos a uma forma\u00e7\u00e3o e a um exame a n\u00edvel das minas e obter um certificado de compet\u00eancia.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 4. O material el\u00e9trico \u00e0 prova de explos\u00e3o deve ser inspeccionado por inspectores \u00e0 prova de explos\u00e3o a tempo inteiro antes de entrar no po\u00e7o, no que diz respeito \u00e0 sua \u201ccertifica\u00e7\u00e3o de produto\u201d, \u201ccertifica\u00e7\u00e3o \u00e0 prova de explos\u00e3o\u201d, \u201cmarca de seguran\u00e7a de produto de mina de carv\u00e3o\u201d e desempenho de seguran\u00e7a; s\u00f3 depois de passar a inspe\u00e7\u00e3o e emitir um certificado de conformidade \u00e9 que ser\u00e1 autorizado a entrar no po\u00e7o. Depois de passar a inspe\u00e7\u00e3o e emitir o certificado de conformidade, o equipamento ser\u00e1 autorizado a entrar no po\u00e7o. Os produtos el\u00e9ctricos \u00e0 prova de explos\u00e3o para opera\u00e7\u00e3o experimental industrial devem ter a \u201clicen\u00e7a de teste industrial\u201d emitida pelo departamento de supervis\u00e3o e inspe\u00e7\u00e3o da qualidade, e as medidas de seguran\u00e7a formuladas pela unidade utilizadora ser\u00e3o examinadas e aprovadas pelo vice-diretor geral da mec\u00e2nica e eletricidade da mina, caso contr\u00e1rio n\u00e3o ser\u00e3o autorizados a entrar no po\u00e7o.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 5. O equipamento el\u00e9trico \u00e0 prova de explos\u00e3o do fundo do po\u00e7o para alterar o valor nominal da utiliza\u00e7\u00e3o e transforma\u00e7\u00e3o t\u00e9cnica, deve ser autorizado pelos departamentos de supervis\u00e3o e inspe\u00e7\u00e3o da qualidade dos produtos mineiros do estado.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 6. Os trabalhos de explora\u00e7\u00e3o, manuten\u00e7\u00e3o e repara\u00e7\u00e3o de material el\u00e9trico subterr\u00e2neo \u00e0 prova de explos\u00e3o devem satisfazer os requisitos t\u00e9cnicos de desempenho \u00e0 prova de explos\u00e3o. Se o material el\u00e9trico estiver danificado, deve ser imediatamente tratado ou substitu\u00eddo, sendo estritamente proibido continuar a utiliz\u00e1-lo.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 7. A manuten\u00e7\u00e3o do inv\u00f3lucro \u00e0 prova de explos\u00e3o deve ser efectuada em conformidade com os \u201cRegulamentos de repara\u00e7\u00e3o de inv\u00f3lucros de equipamento el\u00e9trico \u00e0 prova de explos\u00e3o em minas de carv\u00e3o\u201d e deve ser reparada pela unidade ou pelo fabricante que tenha obtido a qualifica\u00e7\u00e3o de inspe\u00e7\u00e3o \u00e0 prova de explos\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 8. Refor\u00e7ar a inspe\u00e7\u00e3o do desempenho el\u00e9trico \u00e0 prova de explos\u00e3o em utiliza\u00e7\u00e3o subterr\u00e2nea:<\/p>\n\n\n\n<p>&nbsp; &nbsp; (1) Os trabalhadores da manuten\u00e7\u00e3o (inspectores de seguran\u00e7a a tempo parcial) dos aparelhos el\u00e9ctricos antideflagrantes sob a sua jurisdi\u00e7\u00e3o devem inspecionar os aparelhos el\u00e9ctricos antideflagrantes pelo menos uma vez por turno.<\/p>\n\n\n\n<p>&nbsp; &nbsp; (2) Um inspetor antideflagrante a tempo inteiro inspecciona os sistemas el\u00e9ctricos antideflagrantes de uma mina de g\u00e1s elevado ou de uma zona de g\u00e1s elevado de uma mina de g\u00e1s reduzido pelo menos duas vezes por semana. Os sistemas el\u00e9ctricos antideflagrantes das minas de baixo teor de g\u00e1s s\u00e3o inspeccionados uma vez por semana.<\/p>\n\n\n\n<p>&nbsp; &nbsp; (3) O pessoal dos inspectores antideflagrantes a tempo inteiro e a tempo parcial deve satisfazer as necessidades dos trabalhos de inspe\u00e7\u00e3o antideflagrante.<\/p>\n\n\n\n<p>&nbsp; <strong>II. Disposi\u00e7\u00f5es gerais:<\/strong><strong><\/strong><\/p>\n\n\n\n<p>&nbsp; &nbsp; 1. Equipamento el\u00e9trico \u00e0 prova de explos\u00e3o (incluindo pequenos aparelhos el\u00e9ctricos), a utiliza\u00e7\u00e3o do n\u00edvel de tens\u00e3o do cabo n\u00e3o deve ser superior ao seu n\u00edvel de tens\u00e3o nominal, caso contr\u00e1rio \u00e9 considerado perdido.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 2. Se o terminal 9# do interrutor magn\u00e9tico antideflagrante utilizado em minas de alto teor de g\u00e1s, de carv\u00e3o e de g\u00e1s proeminente for ligado \u00e0 terra ou se o inv\u00f3lucro antideflagrante for electrificado por qualquer motivo, considera-se que houve perda de explos\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 3. A utiliza\u00e7\u00e3o de interruptores para controlar as linhas de alimenta\u00e7\u00e3o de entrada e de sa\u00edda dos dispositivos de entrada e de sa\u00edda \u00e9 considerada uma perda de explosivos (exceto no que se refere ao acesso ao rel\u00e9 de dete\u00e7\u00e3o de fugas e \u00e0 alimenta\u00e7\u00e3o do circuito de controlo).<\/p>\n\n\n\n<p>4. Todo o equipamento el\u00e9trico \u00e0 prova de explos\u00e3o deve ser gerido de acordo com os requisitos \u00e0 prova de explos\u00e3o, independentemente do local onde \u00e9 utilizado no subsolo.<strong>&nbsp;<\/strong><strong><\/strong><\/p>\n\n\n\n<p><strong>III<\/strong><strong>, O inv\u00f3lucro \u00e0 prova de explos\u00e3o deve ter sinais claros \u00e0 prova de explos\u00e3o, sinais de seguran\u00e7a de carv\u00e3o. Uma das seguintes condi\u00e7\u00f5es para a perda de explos\u00e3o:<\/strong><strong><\/strong><\/p>\n\n\n\n<p>&nbsp; &nbsp; 1. O inv\u00f3lucro apresenta fissuras, soldadura aberta, deforma\u00e7\u00e3o grave (o comprimento da deforma\u00e7\u00e3o \u00e9 superior a 50 mm e a profundidade da convexidade e da concavidade \u00e9 superior a 5 mm).<\/p>\n\n\n\n<p>&nbsp; &nbsp; 2. Inv\u00f3lucro \u00e0 prova de explos\u00e3o dentro e fora da pele de ferrugem (espessura da pele de ferrugem de 0,2 mm e acima).<\/p>\n\n\n\n<p>&nbsp; &nbsp; 3. A placa transparente do orif\u00edcio de observa\u00e7\u00e3o (janela) da c\u00e2mara \u00e0 prova de explos\u00e3o (cavidade) est\u00e1 solta, partida ou utiliza vidro vulgar.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 4. cavidade \u00e0 prova de explos\u00e3o do equipamento \u00e0 prova de explos\u00e3o diretamente atrav\u00e9s, remover a caixa de jun\u00e7\u00e3o do equipamento \u00e0 prova de explos\u00e3o dentro do assento de isolamento \u00e0 prova de explos\u00e3o.<\/p>\n\n\n\n<p>5. O dispositivo de bloqueio est\u00e1 incompleto, os danos por deforma\u00e7\u00e3o n\u00e3o podem desempenhar o papel de bloqueio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>IV<\/strong><strong>, A superf\u00edcie \u00e0 prova de explos\u00e3o deve ser mantida limpa, intacta e deve ser objeto de medidas antiferrugem.<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>&nbsp; &nbsp; 1. Os par\u00e2metros estruturais da superf\u00edcie da junta antideflagrante devem cumprir as disposi\u00e7\u00f5es que se seguem, caso contr\u00e1rio, \u00e9 considerada uma perda de explos\u00e3o:<\/p>\n\n\n\n<p>&nbsp; &nbsp; (1) a parte estacion\u00e1ria do equipamento el\u00e9trico da superf\u00edcie da junta \u00e0 prova de explos\u00e3o, a superf\u00edcie da junta \u00e0 prova de explos\u00e3o do joystick e do veio e do veio de rolamento e o volume do inv\u00f3lucro correspondente \u00e0 folga m\u00e1xima devem estar em conformidade com as disposi\u00e7\u00f5es do Quadro I. O comprimento m\u00ednimo efetivo do tipo de porta de a\u00e7\u00e3o r\u00e1pida n\u00e3o \u00e9 de 25 mm. O comprimento m\u00ednimo efetivo da superf\u00edcie de junta \u00e0 prova de explos\u00e3o do tipo de porta de a\u00e7\u00e3o r\u00e1pida n\u00e3o pode ser inferior a 25 mm.<\/p>\n\n\n\n<p>&nbsp; &nbsp; (2) A rugosidade m\u00e9dia da superf\u00edcie da junta antideflagrante n\u00e3o deve ser superior a 6,3 \u03bcm.<\/p>\n\n\n\n<p>&nbsp; &nbsp; (3) n\u00e3o h\u00e1 ferrugem na superf\u00edcie do isolamento da explos\u00e3o (esfregada com gaze de algod\u00e3o, ainda h\u00e1 pontos de ferrugem para a ferrugem, deixando apenas a sombra da nuvem, n\u00e3o contada como ferrugem).<\/p>\n\n\n\n<p>&nbsp; &nbsp; (4) Superf\u00edcies de isolamento anti-explos\u00e3o aparafusadas e fixadas:<\/p>\n\n\n\n<p>&nbsp; &nbsp; \u2460 Os parafusos e as anilhas de mola devem estar completos e apertados (o aperto para achatar a anilha \u00e9 qualificado).<\/p>\n\n\n\n<p>&nbsp; &nbsp; \u2461 as especifica\u00e7\u00f5es da arruela de press\u00e3o devem ser compat\u00edveis com o parafuso, (ocasionalmente a arruela de press\u00e3o individual quebra ou perda de elasticidade, verifique a folga \u00e0 prova de explos\u00e3o, se n\u00e3o estiver acima do limite, substitua a arruela de press\u00e3o qualificada n\u00e3o \u00e9 uma perda de explos\u00e3o).<\/p>\n\n\n\n<p>&nbsp; &nbsp; \u2462 Os parafusos ou os orif\u00edcios dos parafusos n\u00e3o podem escorregar por fivela (exceto para a substitui\u00e7\u00e3o de parafusos longos do mesmo di\u00e2metro e fixa\u00e7\u00e3o por porca).<\/p>\n\n\n\n<p>&nbsp; &nbsp; (iv) Para parafusos e orif\u00edcios de parafusos imperme\u00e1veis, o comprimento axial das roscas remanescentes nos parafusos e orif\u00edcios de parafusos ap\u00f3s o aperto deve ser superior a 1,5 vezes a espessura das anilhas de press\u00e3o; a espessura \u00e0 volta e no fundo dos orif\u00edcios dos parafusos deve ser superior a 3 mm.<\/p>\n\n\n\n<p>&nbsp; &nbsp; \u2464 As especifica\u00e7\u00f5es dos parafusos e porcas na mesma pe\u00e7a devem ser as mesmas, e a profundidade dos parafusos de fixa\u00e7\u00e3o de a\u00e7o aparafusados nas porcas n\u00e3o deve ser inferior ao di\u00e2metro dos parafusos.<\/p>\n\n\n\n<p>&nbsp; &nbsp; (vi) O comprimento do parafuso de fixa\u00e7\u00e3o de a\u00e7o do furo escareado no furo do parafuso deve ser maior do que o di\u00e2metro do parafuso, ferro fundido, cobre, pe\u00e7as de alum\u00ednio n\u00e3o inferior a 1,5 vezes o di\u00e2metro do parafuso; se a profundidade do furo do parafuso n\u00e3o for suficiente, deve estar no furo completo.<\/p>\n\n\n\n<p>&nbsp; &nbsp; (vii) A tampa da caixa de deriva\u00e7\u00e3o do motor n\u00e3o deve ser invertida.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 2. Na superf\u00edcie de isolamento de explos\u00e3o, os defeitos dentro do comprimento especificado e o comprimento efetivo mais curto entre o bordo do orif\u00edcio do parafuso e o bordo da superf\u00edcie de isolamento de explos\u00e3o n\u00e3o devem exceder as seguintes disposi\u00e7\u00f5es:<\/p>\n\n\n\n<p>&nbsp; &nbsp; (1) Para o aspeto local do di\u00e2metro n\u00e3o \u00e9 superior a 1 mm; a profundidade n\u00e3o \u00e9 superior a 2 mm de buracos de areia, na superf\u00edcie \u00e0 prova de explos\u00e3o de 40, 25, 15 mm, n\u00e3o mais de 2 por cent\u00edmetro quadrado.<\/p>\n\n\n\n<p>&nbsp; &nbsp; (2) A ferida mec\u00e2nica produzida por acaso, a sua largura e profundidade n\u00e3o s\u00e3o superiores a 0,5 mm, o comprimento efetivo da restante superf\u00edcie n\u00e3o lesionada n\u00e3o \u00e9 inferior a 2\/3 do comprimento especificado.<\/p>\n\n\n\n<p>&nbsp; &nbsp; (3) a superf\u00edcie \u00e0 prova de explos\u00e3o n\u00e3o pode ser pintada (se a pintura for encontrada ao verificar se o intervalo n\u00e3o excede as disposi\u00e7\u00f5es do comprimento da junta sem pintura, o comprimento da junta n\u00e3o \u00e9 inferior ao comprimento das disposi\u00e7\u00f5es dos 2\/3 n\u00e3o \u00e9 uma perda de explos\u00e3o).<\/p>\n\n\n\n<p>&nbsp; &nbsp; 3. Motor \u00e0 prova de explos\u00e3o<\/p>\n\n\n\n<p>&nbsp; &nbsp; (1) A superf\u00edcie de jun\u00e7\u00e3o \u00e0 prova de explos\u00e3o do eixo do motor e o orif\u00edcio do eixo n\u00e3o devem produzir fric\u00e7\u00e3o em condi\u00e7\u00f5es normais de trabalho. Quando \u00e9 utilizada a superf\u00edcie de junta cil\u00edndrica \u00e0 prova de explos\u00e3o, a folga unilateral m\u00ednima entre o veio e o orif\u00edcio do veio n\u00e3o deve ser inferior a 0,075 mm.<\/p>\n\n\n\n<p>&nbsp; &nbsp; (2) Estrutura de rolamento, a folga unilateral m\u00e1xima entre o eixo e o furo do eixo n\u00e3o deve ser superior a 2\/3 do valor especificado no quadro I. <strong>v. Dispositivo de introdu\u00e7\u00e3o de cabos:<\/strong><strong><\/strong><\/p>\n\n\n\n<p>&nbsp; &nbsp; O dispositivo de introdu\u00e7\u00e3o do cabo deve estar completo, \u00edntegro, estanque e bem vedado, e uma das seguintes condi\u00e7\u00f5es deve ser uma falha de explos\u00e3o:<\/p>\n\n\n\n<p>&nbsp; &nbsp; 1. O di\u00e2metro interior do vedante \u00e9 superior ao di\u00e2metro exterior do cabo em mais de 1 mm.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 2. A diferen\u00e7a entre o di\u00e2metro interno do bocal de entrada e o di\u00e2metro externo do anel de veda\u00e7\u00e3o excede o valor especificado no quadro II.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 3. A largura do anel de veda\u00e7\u00e3o \u00e9 inferior a 0,7 vezes o di\u00e2metro exterior do cabo, ou a largura m\u00ednima \u00e9 inferior a 10 mm.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 4. A espessura do anel de veda\u00e7\u00e3o \u00e9 inferior a 0,3 vezes o di\u00e2metro exterior do cabo (exceto para cabos de 70 mil\u00edmetros quadrados e superiores), ou a espessura m\u00ednima \u00e9 inferior a 4 mm.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 5. Vedantes com v\u00e1rios cabos enfiados num \u00fanico orif\u00edcio.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 6. Cortar o anel de veda\u00e7\u00e3o sobre o cabo.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 7. A dureza do anel de veda\u00e7\u00e3o n\u00e3o satisfaz a dureza Sauer 45 graus - 55 graus, o envelhecimento (fissuras, pegajosidade, endurecimento, amolecimento, pulveriza\u00e7\u00e3o, descolora\u00e7\u00e3o e outros fen\u00f3menos), a perda de elasticidade, a deforma\u00e7\u00e3o permanente, a dimens\u00e3o efectiva da folga de ajuste n\u00e3o satisfaz os requisitos da fun\u00e7\u00e3o de veda\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 8. O anel de veda\u00e7\u00e3o n\u00e3o est\u00e1 completamente colocado na bainha do cabo (ou no revestimento do cabo blindado).<\/p>\n\n\n\n<p>&nbsp; &nbsp; 9. Existem outros inv\u00f3lucros entre o anel de veda\u00e7\u00e3o e a bainha do cabo (ou pele de chumbo do cabo blindado); existem enchimentos entre o anel de veda\u00e7\u00e3o e o bocal de alimenta\u00e7\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp;10. S\u00e3o utilizados v\u00e1rios vedantes num bocal de entrada.<\/p>\n\n\n\n<p>&nbsp; &nbsp;11. Dispositivos de introdu\u00e7\u00e3o de cabos com rosca, com engate de rosca de menos de 5 parafusos, com parte roscada de comprimento inferior a 8 mm e menos de 6 parafusos roscados.<\/p>\n\n\n\n<p>&nbsp; &nbsp;12. A precis\u00e3o da rosca \u00e9 inferior ao grau 3 e o passo \u00e9 inferior a 0,7 mm.<\/p>\n\n\n\n<p>&nbsp; &nbsp;13. O bocal de alimenta\u00e7\u00e3o n\u00e3o utilizado n\u00e3o tem anel de veda\u00e7\u00e3o ou deflector; ou o deflector est\u00e1 colocado no interior do anel de veda\u00e7\u00e3o; o di\u00e2metro do deflector \u00e9 inferior ao di\u00e2metro interior do bocal de alimenta\u00e7\u00e3o em mais de 2 mm; a espessura do deflector \u00e9 inferior a 2 mm ou a espessura do deflector \u00e9 inferior a 3 mm quando o di\u00e2metro do deflector \u00e9 igual ou superior a 110 mm (todos os deflectores devem ser zincados).<\/p>\n\n\n\n<p>&nbsp; &nbsp;14. Na utiliza\u00e7\u00e3o do bocal de alimenta\u00e7\u00e3o em espiral, falta de anel met\u00e1lico; incompatibilidade entre o anel met\u00e1lico e o bocal de alimenta\u00e7\u00e3o. (Os bicos de alimenta\u00e7\u00e3o n\u00e3o utilizados podem ser utilizados sem an\u00e9is met\u00e1licos).<\/p>\n\n\n\n<p>&nbsp; &nbsp;15. Depois de o bocal de entrada ser pressionado, n\u00e3o h\u00e1 margem ou o bordo interior do bocal de entrada n\u00e3o consegue pressionar firmemente o anel de veda\u00e7\u00e3o; a face final do anel de veda\u00e7\u00e3o n\u00e3o est\u00e1 em bom contacto com a parede; ou o anel de veda\u00e7\u00e3o pode ser m\u00f3vel.<\/p>\n\n\n\n<p>&nbsp; &nbsp;16. O bocal de alimenta\u00e7\u00e3o de arame do tipo placa de press\u00e3o n\u00e3o tem o parafuso de compress\u00e3o ou o parafuso de compress\u00e3o n\u00e3o est\u00e1 apertado, com uma m\u00e3o pode fazer com que o bocal de alimenta\u00e7\u00e3o de arame trema de forma \u00f3bvia.<\/p>\n\n\n\n<p>&nbsp; &nbsp;17. Bocais de alimenta\u00e7\u00e3o de arame do tipo porca que n\u00e3o podem ser apertados no lugar devido a deforma\u00e7\u00e3o, ferrugem, etc., ou em que o polegar, o indicador e o dedo m\u00e9dio de uma m\u00e3o s\u00e3o utilizados para fazer avan\u00e7ar a porca de compress\u00e3o mais de meia volta no sentido de enroscar.<\/p>\n\n\n\n<p>&nbsp; &nbsp;18 cabo no bocal de entrada que \u00e9 empurrado com uma m\u00e3o na dire\u00e7\u00e3o da entrada do cabo.<\/p>\n\n\n\n<p>&nbsp; &nbsp;19. Quando a caixa de jun\u00e7\u00e3o de cabos blindados de alta tens\u00e3o utiliza borracha isolante, a borracha isolante n\u00e3o \u00e9 preenchida acima da boca de tr\u00eas garfos; a borracha isolante tem fissuras que podem ser relativamente activas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>VI. Liga\u00e7\u00e3o dos cabos:<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>&nbsp; &nbsp; Considera-se que uma liga\u00e7\u00e3o por cabo est\u00e1 fora de servi\u00e7o se se verificar uma das seguintes condi\u00e7\u00f5es:<\/p>\n\n\n\n<p>&nbsp; &nbsp; 1. O cabo n\u00e3o est\u00e1 ligado com um penso quente vulcanizado.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 2. Cabos (incluindo cabos de comunica\u00e7\u00e3o, ilumina\u00e7\u00e3o, sinaliza\u00e7\u00e3o, controlo) se a caixa de jun\u00e7\u00e3o com equipamento n\u00e3o intrinsecamente seguro, n\u00e3o utilizar caixa de jun\u00e7\u00e3o de cabos \u00e0 prova de explos\u00e3o (pertencente ao controlo intrinsecamente seguro de cabos de comunica\u00e7\u00e3o, deve ser utilizada caixa de jun\u00e7\u00e3o intrinsecamente segura);<\/p>\n\n\n\n<p>&nbsp; &nbsp; 3. A liga\u00e7\u00e3o do cabo blindado n\u00e3o utiliza caixa de jun\u00e7\u00e3o, a caixa do meio n\u00e3o \u00e9 preenchida com material de enchimento de isolamento ou o enchimento n\u00e3o \u00e9 uma fuga rigorosa da linha central das juntas;<\/p>\n\n\n\n<p>&nbsp; &nbsp; 4. A extremidade do cabo n\u00e3o est\u00e1 ligada \u00e0 instala\u00e7\u00e3o de equipamento el\u00e9trico \u00e0 prova de explos\u00e3o ou de componentes \u00e0 prova de explos\u00e3o;<\/p>\n\n\n\n<p>&nbsp; &nbsp; 5. Equipamentos e cabos el\u00e9ctricos com condutores expostos;<\/p>\n\n\n\n<p>6. Danos no revestimento de borracha, na bainha do cabo de polietileno reticulado ou no n\u00facleo exposto (cabo blindado com blindagem exposta ou equipamento intrinsecamente seguro ligado ao condutor exposto do cabo, exceto, mas deve ser prontamente reparado).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>VII. Dispositivo de liga\u00e7\u00e3o \u00e0 prova de fogo:<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>&nbsp; &nbsp; 1. O lado da fonte de alimenta\u00e7\u00e3o da ficha do berbequim el\u00e9trico a carv\u00e3o deve ser ligado \u00e0 tomada, a medi\u00e7\u00e3o da carga \u00e9 ligada \u00e0 ficha e a liga\u00e7\u00e3o \u00e9 invertida para ser considerada como uma perda de explos\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 2. A falta de um dispositivo de jun\u00e7\u00e3o que impe\u00e7a o arranque s\u00fabito do dispositivo de desloca\u00e7\u00e3o Xu, a tens\u00e3o de alimenta\u00e7\u00e3o nos 660 volts - 1140 volts do dispositivo de liga\u00e7\u00e3o sem dispositivo de interbloqueio el\u00e9trico \u00e9 considerada como estando fora de perigo de explos\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 3. A ficha de contacto desligada no momento da falha de energia, o inv\u00f3lucro com o di\u00e2metro m\u00e1ximo da diferen\u00e7a de superf\u00edcie de rutura w e o comprimento efetivo m\u00ednimo L, n\u00e3o cumpre as disposi\u00e7\u00f5es do quadro III para a perda de explos\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>VIII. <a href=\"https:\/\/led.amasly.com\/pt\/\">Aparelhos de ilumina\u00e7\u00e3o:<\/a><\/strong><\/h2>\n\n\n\n<p>&nbsp; &nbsp; 1. L\u00e2mpadas e lanternas do tipo de seguran\u00e7a \u00e0 prova de explos\u00e3o para mudar a porta de press\u00e3o para a porta Luo para a perda de explos\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 2. As l\u00e2mpadas e lanternas \u00e0 prova de explos\u00e3o s\u00f3 podem ser abertas ap\u00f3s a desconex\u00e3o da cobertura transparente da fonte de alimenta\u00e7\u00e3o do dispositivo de interbloqueio em caso de falha da explos\u00e3o.<\/p>\n\n\n\n<p>&nbsp; &nbsp; 3. A cobertura de vidro das l\u00e2mpadas e lanternas \u00e0 prova de explos\u00e3o parece solta, rachada, partida, um dos casos de perda de explos\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>IX. Candeeiros de minas:<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>&nbsp; &nbsp;Os candeeiros de minas utilizados no subsolo devem ter a marca de prote\u00e7\u00e3o contra explos\u00f5es e a marca de seguran\u00e7a dos produtos de minas de carv\u00e3o, e uma das seguintes condi\u00e7\u00f5es \u00e9 considerada como perda de explos\u00e3o:<\/p>\n\n\n\n<p>&nbsp; &nbsp;1. Cabe\u00e7a da l\u00e2mpada rachada, anel da cabe\u00e7a da l\u00e2mpada solto, vidro rachado, veda\u00e7\u00e3o deficiente da cabe\u00e7a da l\u00e2mpada, falha do fecho da l\u00e2mpada.<\/p>\n\n\n\n<p>&nbsp; &nbsp;2. A linha da l\u00e2mpada est\u00e1 partida e o fio do n\u00facleo exposto, o dispositivo de introdu\u00e7\u00e3o da linha da l\u00e2mpada est\u00e1 danificado, a veda\u00e7\u00e3o n\u00e3o est\u00e1 apertada, a linha da l\u00e2mpada est\u00e1 a ser adulterada.<\/p>","protected":false},"excerpt":{"rendered":"<p>Coal mine explosion-proof inspection standards I. General provisions: &nbsp; &nbsp; 1. In order to further implement the &#8220;Coal Mine Safety Regulations&#8221; and the standards and regulations on explosion-proof electrics, to improve the understanding of electromechanical workers on the performance of explosion-proof electrics, and to facilitate the mastery of the use of the standards in practical [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2154","post","type-post","status-publish","format-standard","hentry","category-explosion-proof-equipment"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/pt\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"Coal mine explosion-proof inspection standards I. General provisions: &nbsp; &nbsp; 1. In order to further implement the &#8220;Coal Mine Safety Regulations&#8221; and the standards and regulations on explosion-proof electrics, to improve the understanding of electromechanical workers on the performance of explosion-proof electrics, and to facilitate the mastery of the use of the standards in practical&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/posts\/2154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/comments?post=2154"}],"version-history":[{"count":2,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/posts\/2154\/revisions"}],"predecessor-version":[{"id":2304,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/posts\/2154\/revisions\/2304"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/media?parent=2154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/categories?post=2154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/tags?post=2154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}