{"id":2317,"date":"2025-03-07T20:28:37","date_gmt":"2025-03-07T12:28:37","guid":{"rendered":"https:\/\/led.amasly.com\/?page_id=2317"},"modified":"2026-01-22T11:44:38","modified_gmt":"2026-01-22T03:44:38","slug":"indoor-stadium-intelligent-lighting-solutions","status":"publish","type":"page","link":"https:\/\/led.amasly.com\/pt\/solutions\/indoor-stadium-intelligent-lighting-solutions\/","title":{"rendered":"Solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-27bae773 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\"><strong>Solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores<\/strong><\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Introdu\u00e7\u00e3o de solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores<\/h2>\n\n\n\n<p>Com o desenvolvimento gradual da economia de mercado socialista, a constru\u00e7\u00e3o de instala\u00e7\u00f5es desportivas na ideologia orientadora para realizar a fun\u00e7\u00e3o, opera\u00e7\u00e3o, servi\u00e7o nos tr\u00eas aspectos da transforma\u00e7\u00e3o, de modo que a ind\u00fastria do desporto fora do mundo estreito e para a comunidade, para o mercado.<\/p>\n\n\n\n<p>Os recintos desportivos modernos, n\u00e3o s\u00f3 exigem que o edif\u00edcio tenha uma apar\u00eancia bonita e generosa, uma variedade de equipamentos desportivos completos e perfeitos, ao mesmo tempo que devem ter um bom ambiente de ilumina\u00e7\u00e3o, adequado, ilumina\u00e7\u00e3o e brilho uniformes, cor de luz ideal, tridimensional e sem brilho, etc., estas condi\u00e7\u00f5es s\u00e3o o padr\u00e3o moderno do est\u00e1dio. Do ponto de vista da ilumina\u00e7\u00e3o, um projeto de ilumina\u00e7\u00e3o de um est\u00e1dio, a fun\u00e7\u00e3o dos factores mais importantes a considerar \u00e9 satisfazer as necessidades visuais das pessoas, quer sejam desportistas, espectadores ou pessoal; a escolha ideal do controlo deve ser inteligente, o que \u00e9 vital para o modelo de gest\u00e3o moderno do local, bem como para a experi\u00eancia do utilizador. Qu\u00e3o inteligente \u00e9 a ilumina\u00e7\u00e3o dos est\u00e1dios?<\/p>\n\n\n\n<p>Os sistemas inteligentes de controlo da ilumina\u00e7\u00e3o para est\u00e1dios fornecem solu\u00e7\u00f5es avan\u00e7adas de ilumina\u00e7\u00e3o para recintos desportivos. Ao ligar os circuitos de ilumina\u00e7\u00e3o ao sistema inteligente, os modos de comuta\u00e7\u00e3o e regula\u00e7\u00e3o dos circuitos de ilumina\u00e7\u00e3o podem ser facilmente editados e os pain\u00e9is de controlo dos modos correspondentes podem ser definidos de acordo com as necessidades dos diferentes eventos desportivos e tarefas de desempenho. Este sistema tem uma fun\u00e7\u00e3o de comuta\u00e7\u00e3o de execu\u00e7\u00e3o irrevers\u00edvel, assegurando que o mesmo modo \u00e9 executado para m\u00faltiplas opera\u00e7\u00f5es e evitando erros de opera\u00e7\u00e3o.<\/p>\n\n\n\n<p>Este sistema de ilumina\u00e7\u00e3o inteligente foi concebido para o recinto desportivo do centro desportivo. O centro desportivo \u00e9 um espa\u00e7o desportivo completo que integra uma sala de basquetebol, uma sala de badminton, uma sala de t\u00e9nis de mesa e uma \u00e1rea de descanso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores\uff1aFun\u00e7\u00f5es de controlo inteligente:<\/h2>\n\n\n\n<p>1. Fun\u00e7\u00e3o de temporiza\u00e7\u00e3o<\/p>\n\n\n\n<p>2. Fun\u00e7\u00e3o combinada de dete\u00e7\u00e3o do corpo humano<\/p>\n\n\n\n<p>3. Controlo de zona\/controlo geral<\/p>\n\n\n\n<p>4. Fun\u00e7\u00e3o de comuta\u00e7\u00e3o de cenas personalizada<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores\uff1a<strong>Solu\u00e7\u00e3o de ilumina\u00e7\u00e3o para campos de basquetebol<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-8528ac8a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72471-5.png 762w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72471-5-300x207.png 300w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72471-5.png\" alt=\"Indoor stadium intelligent lighting solutions\uff1a\" class=\"uag-image-2318\" width=\"762\" height=\"527\" title=\"Solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores\uff1a\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p>Devido \u00e0 considera\u00e7\u00e3o do treino de basquetebol como o principal programa do campo, o local cobre uma grande \u00e1rea, as l\u00e2mpadas e lanternas de controlo s\u00e3o mais, a utiliza\u00e7\u00e3o global do sistema de bus CAN. O sistema \u00e9 flex\u00edvel e vai ao encontro do conceito de funcionamento inovador e amigo do ambiente.<\/p>\n\n\n\n<p>A ilumina\u00e7\u00e3o do campo pode ser configurada at\u00e9 12 modos de ilumina\u00e7\u00e3o, de acordo com a necessidade de realizar de forma flex\u00edvel uma variedade de cen\u00e1rios, tais como \u201cjogo oficial\u201d, \u201cmodo de treino\u201d, \u201ccontrolo total\u201d e outros modos de ilumina\u00e7\u00e3o. Modo.<\/p>\n\n\n\n<p>Modo de jogo: todas as luzes do campo de basquetebol est\u00e3o acesas para os espectadores.<\/p>\n\n\n\n<p>Modo de treino: Todas as luzes do campo de treinos est\u00e3o acesas.<\/p>\n\n\n\n<p>Modo de limpeza: todas as luzes se acendem em 2 intervalos.<\/p>\n\n\n\n<p>Controlo principal: Um bot\u00e3o para controlar o ligar\/desligar das luzes.<\/p>\n\n\n\n<p>As luzes brilham uniformemente no campo desportivo, a ilumina\u00e7\u00e3o m\u00e9dia do campo de basquetebol e do p\u00fablico cumpre os requisitos de ilumina\u00e7\u00e3o das competi\u00e7\u00f5es profissionais, criando uma atmosfera competitiva para as competi\u00e7\u00f5es de basquetebol e iluminando a paix\u00e3o dos jogadores pelo tiro!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores\uff1a<strong>Solu\u00e7\u00e3o de ilumina\u00e7\u00e3o do campo de badminton<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-d2a9a451 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72473-3.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72473-3.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72473-3.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72473-3.png\" alt=\"\" class=\"uag-image-2319\" width=\"762\" height=\"461\" title=\"\u56fe\u72473\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<p>O campo de badminton \u00e9 o local exclusivo para a pr\u00e1tica do badminton, onde os atletas demonstram as suas capacidades e os entusiastas se divertem no espa\u00e7o desportivo. N\u00e3o s\u00f3 proporciona a \u00e1rea f\u00edsica necess\u00e1ria para as actividades de badminton, como tamb\u00e9m promove a divulga\u00e7\u00e3o do esp\u00edrito desportivo e da comunica\u00e7\u00e3o. Desde a prepara\u00e7\u00e3o f\u00edsica di\u00e1ria at\u00e9 aos torneios profissionais, o campo de badminton \u00e9 o principal suporte para promover o desenvolvimento do badminton.<\/p>\n\n\n\n<p>Impacto da ilumina\u00e7\u00e3o do campo de badminton no local<\/p>\n\n\n\n<p>Experi\u00eancia visual: uma boa ilumina\u00e7\u00e3o permite aos jogadores determinar claramente a trajet\u00f3ria de voo, a velocidade e o ponto de aterragem da bola, reduzindo os erros visuais e melhorando a fluidez e o espet\u00e1culo do jogo. Uma ilumina\u00e7\u00e3o fraca ou irregular obstrui a vis\u00e3o dos atletas e afecta o seu jogo.<\/p>\n\n\n\n<p>Atmosfera do local: uma ilumina\u00e7\u00e3o adequada cria uma atmosfera desportiva confort\u00e1vel, quer se trate de um jogo di\u00e1rio de lazer ou de uma competi\u00e7\u00e3o intensa, a ilumina\u00e7\u00e3o correta pode tornar os participantes mais concentrados e empenhados.<\/p>\n\n\n\n<p>Torneios de badminton nos requisitos do campo de badminton<\/p>\n\n\n\n<p>Eventos amadores: os requisitos de ilumina\u00e7\u00e3o s\u00e3o relativamente b\u00e1sicos, principalmente para garantir um certo grau de uniformidade da ilumina\u00e7\u00e3o, de modo a que os jogadores possam ver a bola e os limites do campo. Ilumina\u00e7\u00e3o geral de cerca de 300 - 500 lx.<\/p>\n\n\n\n<p>Torneios profissionais: Os requisitos s\u00e3o extremamente rigorosos, n\u00e3o s\u00f3 \u00e9 necess\u00e1ria uma ilumina\u00e7\u00e3o elevada, normalmente acima de 1000 lx, mas tamb\u00e9m uma elevada uniformidade da ilumina\u00e7\u00e3o para evitar \u00e1reas claras e escuras desiguais. Ao mesmo tempo, o controlo do brilho tamb\u00e9m \u00e9 muito importante, para n\u00e3o afetar a vis\u00e3o dos jogadores e dos espectadores. &nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores\uff1a<strong>Programa de ilumina\u00e7\u00e3o do pavilh\u00e3o de t\u00e9nis de mesa<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>An\u00e1lise da norma de ilumina\u00e7\u00e3o do pavilh\u00e3o de t\u00e9nis de mesa<\/strong><strong><\/strong><\/h3>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-11c4b3c0 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/pt\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72474-1.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72474-1.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72474-1.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72474-1.png\" alt=\"\" class=\"uag-image-2320\" width=\"761\" height=\"334\" title=\"\u56fe\u72474\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n\n\n\n<p>1. ilumina\u00e7\u00e3o do n\u00edvel de forma\u00e7\u00e3o<\/p>\n\n\n\n<p>Requisitos de ilumina\u00e7\u00e3o: 300-500 lx &nbsp;<\/p>\n\n\n\n<p>Cenas aplic\u00e1veis: treino di\u00e1rio, actividades amadoras &nbsp;<\/p>\n\n\n\n<p>Carater\u00edsticas: Para satisfazer as necessidades visuais b\u00e1sicas, a uniformidade da ilumina\u00e7\u00e3o (U0) deve ser superior a 0,7.<\/p>\n\n\n\n<p>2. ilumina\u00e7\u00e3o de n\u00edvel de evento amador<\/p>\n\n\n\n<p>Requisitos de ilumina\u00e7\u00e3o: 750-1000 lx &nbsp;<\/p>\n\n\n\n<p>Cen\u00e1rios aplic\u00e1veis: concursos locais, concursos de clubes &nbsp;<\/p>\n\n\n\n<p>Carater\u00edsticas: a necessidade de ter em conta o conforto visual dos atletas e a experi\u00eancia de visualiza\u00e7\u00e3o do p\u00fablico, o \u00edndice de restitui\u00e7\u00e3o de cores (Ra) deve ser superior a 80.<\/p>\n\n\n\n<p>3. ilumina\u00e7\u00e3o profissional para eventos<\/p>\n\n\n\n<p>Requisitos de ilumina\u00e7\u00e3o: 1500-1800 lx &nbsp;<\/p>\n\n\n\n<p>Cenas aplic\u00e1veis: eventos internacionais, emiss\u00f5es de televis\u00e3o &nbsp;<\/p>\n\n\n\n<p>Carater\u00edsticas: Para cumprir os requisitos da radiodifus\u00e3o de alta defini\u00e7\u00e3o, o r\u00e1cio entre a ilumina\u00e7\u00e3o vertical e a ilumina\u00e7\u00e3o horizontal deve ser pr\u00f3ximo de 1:1,2 e o \u00edndice de restitui\u00e7\u00e3o de cor (Ra) deve ser superior a 90.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Requisitos de ilumina\u00e7\u00e3o do pavilh\u00e3o de t\u00e9nis de mesa<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>A disposi\u00e7\u00e3o da ilumina\u00e7\u00e3o de uma sala de t\u00e9nis de mesa deve seguir princ\u00edpios \u00f3pticos cient\u00edficos para garantir uma distribui\u00e7\u00e3o uniforme da luz e um controlo eficaz do encandeamento. Os pontos-chave da disposi\u00e7\u00e3o s\u00e3o os seguintes:<\/p>\n\n\n\n<p>1. Altura e \u00e2ngulo de instala\u00e7\u00e3o da l\u00e2mpada<\/p>\n\n\n\n<p>As lumin\u00e1rias devem ser instaladas a uma altura n\u00e3o inferior a 6 metros para garantir que a luz cobre toda a \u00e1rea de jogo. &nbsp;<\/p>\n\n\n\n<p>O \u00e2ngulo de proje\u00e7\u00e3o das l\u00e2mpadas deve ser controlado entre 25\u00b0 e 35\u00b0 para evitar a interfer\u00eancia direta da luz na vis\u00e3o dos atletas.<\/p>\n\n\n\n<p>2. Controlo do encandeamento<\/p>\n\n\n\n<p>O \u00edndice de encandeamento (GR) deve ser controlado abaixo de 30, sendo o GR\u226422 exigido para eventos profissionais. &nbsp;<\/p>\n\n\n\n<p>O design de distribui\u00e7\u00e3o assim\u00e9trica da luz \u00e9 utilizado para reduzir a luz diretamente no campo de vis\u00e3o do atleta.<\/p>\n\n\n\n<p>3. Uniformidade da ilumina\u00e7\u00e3o<\/p>\n\n\n\n<p>A uniformidade de ilumina\u00e7\u00e3o (U0) da zona de competi\u00e7\u00e3o deve ser superior a 0,8 para garantir a visibilidade da esfera em movimentos de alta velocidade. &nbsp;<\/p>\n\n\n\n<p>A ilumina\u00e7\u00e3o da zona perif\u00e9rica n\u00e3o deve ser inferior a 70% da zona central.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores\uff1a<strong>Programa de ilumina\u00e7\u00e3o de corredores<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-1dce91ec wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/pt\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72475.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72475.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72475.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u72475.png\" alt=\"\" class=\"uag-image-2321\" width=\"761\" height=\"461\" title=\"\u56fe\u72475\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n\n\n\n<p>9:00 - 10:00<\/p>\n\n\n\n<p>O sensor do corpo humano \u00e9 ativado: a luz acende-se quando as pessoas chegam e apaga-se quando as pessoas saem.<\/p>\n\n\n\n<p>10:00 p.m. - 9:00 a.m.<\/p>\n\n\n\n<p>O sensor do corpo humano desliga-se.<\/p>\n\n\n\n<p>(1) Realizar um controlo inteligente da ilumina\u00e7\u00e3o, melhorar o n\u00edvel de gest\u00e3o da ilumina\u00e7\u00e3o do gin\u00e1sio e reduzir os custos de manuten\u00e7\u00e3o.<\/p>\n\n\n\n<p>(2) Realizar efeitos de controlo da ilumina\u00e7\u00e3o ricos e diversificados; poupan\u00e7a de energia e cria\u00e7\u00e3o de um ambiente luminoso saud\u00e1vel.<\/p>\n\n\n\n<p>(3) Pode tamb\u00e9m ser ligado a outros sistemas, sistemas ambientais, sistemas de inc\u00eandio, etc.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Solu\u00e7\u00f5es de ilumina\u00e7\u00e3o inteligente para est\u00e1dios interiores\uff1a<strong>Os elementos fundamentais do design de ilumina\u00e7\u00e3o profissional<\/strong><\/h2>\n\n\n\n<p>1. Reprodu\u00e7\u00e3o de cores e reprodu\u00e7\u00e3o de cores: O t\u00e9nis de mesa exige um elevado grau de reconhecimento das cores, especialmente o contraste entre a bola e o fundo. A ilumina\u00e7\u00e3o profissional tem de garantir que o \u00edndice de restitui\u00e7\u00e3o de cores (Ra) \u00e9 superior a 90, de modo a restaurar verdadeiramente a cor da bola e a trajet\u00f3ria do movimento.<\/p>\n\n\n\n<p>2. Estrobosc\u00f3pio e estabilidade: um estrobosc\u00f3pio elevado afecta a avalia\u00e7\u00e3o visual dos atletas, a profundidade da flutua\u00e7\u00e3o do estrobosc\u00f3pio do sistema de ilumina\u00e7\u00e3o profissional deve ser controlada abaixo de 1% para garantir a estabilidade da luz.<\/p>\n\n\n\n<p>3. Poupan\u00e7a de energia e prote\u00e7\u00e3o do ambiente: a ilumina\u00e7\u00e3o desportiva moderna tem de ter em conta a efici\u00eancia energ\u00e9tica e a prote\u00e7\u00e3o do ambiente, a utiliza\u00e7\u00e3o de uma fonte de luz LED de alta efici\u00eancia e de um sistema de ilumina\u00e7\u00e3o inteligente pode reduzir o consumo de energia em mais de 30%.<\/p>\n\n\n\n<p>No programa de design de ilumina\u00e7\u00e3o do gin\u00e1sio, o sistema inteligente incorpora plenamente as vantagens dos programas inteligentes para reduzir o consumo, atrav\u00e9s da cria\u00e7\u00e3o de efeitos de ilumina\u00e7\u00e3o diversificados para demonstrar ainda mais a combina\u00e7\u00e3o verde e apaixonada das necessidades do conceito desportivo. No futuro, continuaremos a ajudar os clientes a concretizar a procura de poupan\u00e7a de energia e redu\u00e7\u00e3o do consumo.<\/p>\n\n\n\n<p>Padr\u00e3o: <a href=\"http:\/\/www.iec.com\" rel=\"nofollow noopener\" target=\"_blank\">IEC 60598<\/a><\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c7d898dd alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Produtos relacionados<\/h2>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-66e4defc alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a42945f9\">\n<div class=\"wp-block-uagb-image uagb-block-7296296b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/pt\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png\" alt=\"\" class=\"uag-image-1495\" width=\"300\" height=\"300\" title=\"Luzes de ba\u00eda alta \u00e0 prova de explos\u00e3o\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4d3efde5\">\n<div class=\"wp-block-uagb-image uagb-block-c9e90797 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/pt\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png\" alt=\"\" class=\"uag-image-1132\" width=\"300\" height=\"300\" title=\"Luzes LED \u00e0 prova de tripla prote\u00e7\u00e3o2\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-11c2578b\">\n<div class=\"wp-block-uagb-image uagb-block-6e8883aa wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/pt\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png\" alt=\"\" class=\"uag-image-1501\" width=\"300\" height=\"300\" title=\"Luz LED para esta\u00e7\u00e3o de servi\u00e7o \u00e0 prova de explos\u00e3o\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-548945b5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-967755d5\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/pt\/products\/\">Luzes LED \u00e0 prova de explos\u00e3o<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9bc52fc2\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/pt\/products\/\">Luzes LED Tri-Proof<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8ffa0a23\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/pt\/products\/\">Luzes para postos de gasolina \u00e0 prova de explos\u00e3o<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-29499fe0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-777ee1c7\">\n<div class=\"wp-block-uagb-image uagb-block-2e9a1851 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/pt\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg\" alt=\"\" class=\"uag-image-1526\" width=\"300\" height=\"300\" title=\"Holofote LED 50W 100W 150W 200W 300W\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-af8c8683\">\n<div class=\"wp-block-uagb-image uagb-block-67947854 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/pt\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png\" alt=\"\" class=\"uag-image-1130\" width=\"300\" height=\"300\" title=\"luz led-tri-proof\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0fdfdd58\">\n<div class=\"wp-block-uagb-image uagb-block-1187d32d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/pt\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg\" alt=\"\" class=\"uag-image-1145\" width=\"300\" height=\"300\" title=\"Luz de rua LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6a60882c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-f1e91a35\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/pt\/products\/\">Luzes de inunda\u00e7\u00e3o LED<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-165bfa58\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/pt\/products\/\">Tubos de luz LED \u00e0 prova de tripla prote\u00e7\u00e3o<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f6096e3b\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/pt\/products\/\">Luzes de rua LED<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-99c0e0a5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Indoor stadium intelligent lighting solutions Indoor stadium intelligent lighting solutions introduce With the gradual development of the socialist market economy, the construction of sports venues in the guiding ideology to realize the function, operation, service on the three aspects of the transformation, so that the sports industry out of the narrow world and towards the [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1808,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2317","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/pt\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"Indoor stadium intelligent lighting solutions Indoor stadium intelligent lighting solutions introduce With the gradual development of the socialist market economy, the construction of sports venues in the guiding ideology to realize the function, operation, service on the three aspects of the transformation, so that the sports industry out of the narrow world and towards the&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/pages\/2317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/comments?post=2317"}],"version-history":[{"count":2,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/pages\/2317\/revisions"}],"predecessor-version":[{"id":4568,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/pages\/2317\/revisions\/4568"}],"up":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/pages\/1808"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/pt\/wp-json\/wp\/v2\/media?parent=2317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}