{"id":1610,"date":"2024-12-30T22:33:12","date_gmt":"2024-12-30T14:33:12","guid":{"rendered":"https:\/\/led.amasly.com\/?p=1610"},"modified":"2024-12-30T22:34:14","modified_gmt":"2024-12-30T14:34:14","slug":"the-impact-of-low-temperature-on-intrinsically-safe-i-type-explosion-proof-lamps","status":"publish","type":"post","link":"https:\/\/led.amasly.com\/it\/light\/the-impact-of-low-temperature-on-intrinsically-safe-i-type-explosion-proof-lamps\/","title":{"rendered":"L'impatto della bassa temperatura sulle lampade antideflagranti a sicurezza intrinseca di tipo \u201ci\u201d"},"content":{"rendered":"<p class=\"has-medium-font-size\">Le temperature ambientali inferiori a -20 \u2103 possono influire sul tipo di protezione antideflagrante dell'apparecchiatura e devono essere prese in considerazione durante la valutazione e il collaudo dell'apparecchiatura. <\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-55316f07 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights.jpg\" alt=\"\" class=\"uag-image-1600\" width=\"1008\" height=\"341\" title=\"Luci a prova di esplosione\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Per le apparecchiature a sicurezza intrinseca, a basse temperature cambiano le caratteristiche prestazionali dei componenti utilizzati nelle apparecchiature a sicurezza intrinseca, come le barriere di sicurezza e gli alimentatori a scintilla limitata con componenti dinamici a sicurezza intrinseca. Quando si scelgono i componenti, si deve tenere conto di queste variazioni e la valutazione deve essere condotta in conformit\u00e0 ai requisiti della corrispondente \u201cApparecchiatura a sicurezza intrinseca \u2018i\u2019 protetta\u201d, utilizzando la temperatura di esercizio specificata dal produttore. Questo valore nominale deve tenere conto dei cambiamenti nel funzionamento dei componenti a semiconduttore che influenzano le prestazioni a sicurezza intrinseca per fornire la funzione a sicurezza intrinseca richiesta. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Le prestazioni di sicurezza intrinseca dell'alimentatore con componenti dinamici a sicurezza intrinseca utilizzato in tali sistemi dipendono dalla temperatura ambiente del sito di applicazione. A basse temperature, la sensibilit\u00e0 dei componenti dinamici a semiconduttore dell'alimentatore a sicurezza intrinseca diminuisce e il tempo di commutazione aumenta. Le norme in materia stabiliscono che il test di accensione a scintilla deve essere condotto nella disposizione del circuito pi\u00f9 soggetta all'accensione. Tuttavia, nella pratica, i test vengono solitamente eseguiti a temperature di laboratorio. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Pertanto, per i sistemi con alimentatori a sicurezza intrinseca di natura dinamica in aree che comportano basse temperature, le prestazioni a sicurezza intrinseca devono essere testate alle temperature comprese nell'intervallo di applicazione, inclusa la temperatura pi\u00f9 bassa dei componenti dinamici a semiconduttore, e a condizione che il dispositivo di prova delle scintille sia collegato a un carico appropriato alla temperatura operativa pi\u00f9 elevata. I componenti a semiconduttore che offrono una protezione a sicurezza intrinseca a una temperatura ambiente inferiore a -40 \u2103 possono richiedere sistemi di riscaldamento speciali. Per le apparecchiature utilizzate in climi marini freddi, sebbene l'apparecchiatura sia conforme alla distanza di dispersione e all'indice di tracciamento comparativo (CTI) dei materiali isolanti, potrebbe essere necessario un livello di protezione superiore a IP54 per garantire che i depositi di cloruro sulla superficie dei circuiti stampati non causino tracciamento.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ambient temperatures below -20 \u2103 may affect the explosion-proof type of the equipment, and should be taken into account during equipment evaluation and testing. For intrinsically safe equipment, at low temperatures, the performance characteristics of components used in intrinsically safe equipment, such as safety barriers, and the spark-limited power supplies with dynamic intrinsically safe components [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1600,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-light"],"uagb_featured_image_src":{"full":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights.jpg",1008,341,false],"thumbnail":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights-150x150.jpg",150,150,true],"medium":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights-300x101.jpg",300,101,true],"medium_large":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights-768x260.jpg",768,260,true],"large":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights.jpg",1008,341,false],"1536x1536":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights.jpg",1008,341,false],"2048x2048":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights.jpg",1008,341,false],"trp-custom-language-flag":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/Explosion-proof-lights.jpg",18,6,false]},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/it\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"Ambient temperatures below -20 \u2103 may affect the explosion-proof type of the equipment, and should be taken into account during equipment evaluation and testing. For intrinsically safe equipment, at low temperatures, the performance characteristics of components used in intrinsically safe equipment, such as safety barriers, and the spark-limited power supplies with dynamic intrinsically safe components&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/posts\/1610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/comments?post=1610"}],"version-history":[{"count":1,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/posts\/1610\/revisions"}],"predecessor-version":[{"id":1611,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/posts\/1610\/revisions\/1611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/media\/1600"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/media?parent=1610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/categories?post=1610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/tags?post=1610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}