{"id":1589,"date":"2024-12-28T14:34:33","date_gmt":"2024-12-28T06:34:33","guid":{"rendered":"https:\/\/led.amasly.com\/?p=1589"},"modified":"2024-12-28T14:52:01","modified_gmt":"2024-12-28T06:52:01","slug":"the-relevant-requirements-for-grounding-of-explosion-proof-lamps-and-electrical-equipment-in-explosive-hazardous-environments","status":"publish","type":"post","link":"https:\/\/led.amasly.com\/it\/explosion-proof-equipment\/the-relevant-requirements-for-grounding-of-explosion-proof-lamps-and-electrical-equipment-in-explosive-hazardous-environments\/","title":{"rendered":"I requisiti rilevanti per la messa a terra di lampade e apparecchiature elettriche antideflagranti in ambienti a rischio di esplosione."},"content":{"rendered":"<p class=\"has-medium-font-size\">Negli ambienti a rischio di esplosione, le parti metalliche non caricate esposte delle apparecchiature elettriche, come gli involucri metallici, le strutture metalliche, le apparecchiature installate su strutture metalliche messe a terra, le tubazioni metalliche e i relativi raccordi, le guaine di protezione dei cavi e le guaine metalliche dei cavi, ecc. devono essere messe a terra. Molti standard hanno stabilito norme chiare sui requisiti di messa a terra delle apparecchiature elettriche in ambienti a rischio di esplosione. <\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-5d6c6f99 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png\" alt=\"\" class=\"uag-image-1590\" width=\"469\" height=\"305\" title=\"messa a terra delle lampade antideflagranti\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<p class=\"has-medium-font-size\">Le impostazioni dei fili di messa a terra per le apparecchiature elettriche devono essere trattate in modo diverso a seconda delle aree pericolose e dei tipi di apparecchiature elettriche. Gli involucri metallici di tutte le apparecchiature elettriche in ambienti esplosivi, indipendentemente dal fatto che siano installati su strutture metalliche messe a terra, devono essere messi a terra. I requisiti pertinenti sono i seguenti: <\/p>\n\n\n\n<p class=\"has-medium-font-size\">1) Tutte le apparecchiature elettriche in ambiente esplosivo Zona 1, Zona 20 e Zona 21, nonch\u00e9 tutte le apparecchiature elettriche ad eccezione degli apparecchi di illuminazione in ambiente esplosivo Zona 2 e Zona 22, devono essere dotate di fili di messa a terra dedicati. Nota: se il cavo di messa a terra dedicato \u00e8 posato nella stessa guaina protettiva del cavo di fase, deve avere lo stesso livello di isolamento del cavo di fase. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">2) Per gli apparecchi di illuminazione in ambiente esplosivo Zona 2 e Zona 22, \u00e8 possibile utilizzare un sistema di tubazioni metalliche di collegamento elettrico affidabile come filo di messa a terra, ma non \u00e8 possibile utilizzare tubazioni per il trasporto di sostanze pericolose esplosive. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">3) I fili di messa a terra dedicati alle apparecchiature elettriche e agli apparecchi di illuminazione devono essere collegati separatamente alla rete di messa a terra e il filo neutro di lavoro del circuito elettrico non deve essere utilizzato come filo di messa a terra di protezione. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">4) Il collegamento tra le apparecchiature elettriche in ambienti a rischio di esplosione e il cavo di messa a terra deve utilizzare preferibilmente un cavo a trefoli flessibili a pi\u00f9 fili, con una sezione trasversale minima del filo di rame non inferiore a 4 mm\u00b2. I tubi di protezione devono essere installati nelle parti soggette a danni meccanici. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">5) Quando i cavi blindati vengono introdotti in un'apparecchiatura elettrica, il filo di messa a terra deve essere collegato al bullone di messa a terra all'interno dell'apparecchiatura; il nastro d'acciaio e l'involucro metallico devono essere collegati al bullone di messa a terra esterno dell'apparecchiatura. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">6) I bulloni utilizzati per la messa a terra o per il collegamento a zero in ambienti a rischio di esplosione devono essere dotati di dispositivi antiallentamento; prima di stringere il filo di messa a terra, i terminali di messa a terra e gli elementi di fissaggio devono essere rivestiti con grasso per composti di potenza. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Esistono numerosi requisiti di messa a terra per le apparecchiature elettriche in ambienti a rischio di esplosione. Nel processo di progettazione e installazione, oltre a soddisfare i requisiti di cui sopra, \u00e8 necessario seguire anche gli standard pertinenti.<\/p>","protected":false},"excerpt":{"rendered":"<p>In explosive hazardous environments, the exposed non-charged metal parts of electrical equipment such as the metal enclosures, metal frameworks, equipment installed on grounded metal structures, metal piping and its fittings, cable protection conduits, and the metal sheaths of cables, etc., should all be grounded. Many standards have made clear regulations on the grounding requirements for [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1590,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-explosion-proof-equipment"],"uagb_featured_image_src":{"full":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png",469,305,false],"thumbnail":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps-150x150.png",150,150,true],"medium":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps-300x195.png",300,195,true],"medium_large":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png",469,305,false],"large":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png",469,305,false],"1536x1536":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png",469,305,false],"2048x2048":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png",469,305,false],"trp-custom-language-flag":["https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/12\/grounding-of-explosion-proof-lamps.png",18,12,false]},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/it\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"In explosive hazardous environments, the exposed non-charged metal parts of electrical equipment such as the metal enclosures, metal frameworks, equipment installed on grounded metal structures, metal piping and its fittings, cable protection conduits, and the metal sheaths of cables, etc., should all be grounded. Many standards have made clear regulations on the grounding requirements for&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/posts\/1589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/comments?post=1589"}],"version-history":[{"count":1,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/posts\/1589\/revisions"}],"predecessor-version":[{"id":1591,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/posts\/1589\/revisions\/1591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/media\/1590"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/media?parent=1589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/categories?post=1589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/tags?post=1589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}