{"id":4964,"date":"2026-01-31T15:03:40","date_gmt":"2026-01-31T07:03:40","guid":{"rendered":"https:\/\/led.amasly.com\/?page_id=4964"},"modified":"2026-01-31T15:03:45","modified_gmt":"2026-01-31T07:03:45","slug":"bay82-led-explosion-proof-street-lights","status":"publish","type":"page","link":"https:\/\/led.amasly.com\/it\/products\/explosion-proof-lights\/bay82-led-explosion-proof-street-lights\/","title":{"rendered":"BAY82 Luci stradali a LED antideflagranti"},"content":{"rendered":"<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e407eb08 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-7c0a134c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">BAY82 50W 100W 150W 200W 250W LED Luci di via a prova di esplosione<\/h1>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5d28ec94 default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-462981e6\">\n<div class=\"wp-block-uagb-container uagb-block-6f08c8e4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-b229cb92\">\n<h3 class=\"wp-block-heading\">Contenuto<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-container-core-buttons-is-layout-45b20515 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/products\/explosion-proof-lights\/\">Luci a prova di esplosione<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/products\/ex-proof-electrical-appliance\/\">Apparecchio elettrico a prova di Ex<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/products\/led-tri-proof-light-2\/\">Luce a LED a prova di inciampo<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/products\/led-high-bay-light\/\">Alta luce della baia a LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/products\/led-flood-lights\/\">Luce di inondazione a LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/products\/led-street-lights\/\">Illuminazione stradale a LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/products\/solar-lights\/\">Luce solare a LED<\/a><\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">Contatto<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Email: sales01@amasly.com<strong> <\/strong>      <\/li>\n\n\n\n<li>Cellulare: +86 13732643699                   <\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-uagb-container uagb-block-064256a4\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-uagb-image uagb-block-f7623661 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/10\/explosion-proof-street-lights-1.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/10\/explosion-proof-street-lights-1.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/10\/explosion-proof-street-lights-1.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/10\/explosion-proof-street-lights-1.jpg\" alt=\"explosion proof street lights, ATEX LED street lights, ATEX street light\uff0c Explosion proof\u00a0street lamps\uff0c Explosion proof street light, Explosion proof street light 200watts\" class=\"uag-image-4262\" width=\"300\" height=\"300\" title=\"Lampioni LED ATEX, lampioni a prova di esplosione\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Ambito di applicazione<\/p>\n\n\n\n<p>1. ampiamente utilizzato nell'estrazione petrolifera, nella raffinazione del petrolio, nel settore chimico, militare e in altri luoghi ambientali pericolosi della fabbrica e dell'illuminazione stradale<\/p>\n\n\n\n<p>2. adatto all'ambiente costiero, fluviale e ad altre condizioni di pressione e velocit\u00e0 del vento;<\/p>\n\n\n\n<p>3. adatto a migliaia di ambienti con gas esplosivi della zona 1, zona 2;<\/p>\n\n\n\n<p>4. adatto a migliaia di ambienti con polvere combustibile 21 zone, 22 zone;<\/p>\n\n\n\n<p>5. Adatto per ambienti con gas esplosivi IIA, IIB, IIC. Classe I, Divisione 2, Gruppi A, B, C, D.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-201e76d4\">\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Moel<\/td><td>Potenza<\/td><td>Marchio Ex<\/td><td>Tasso IP<\/td><td>Efficienza luminosa<\/td><td>Tensione<\/td><td>CCT<\/td><td>PF<\/td><\/tr><tr><td>BAY82<\/td><td>50W-300W<\/td><td>Ex d IIC T6<\/td><td>IP66<\/td><td>130lm\/w<\/td><td>Ac85-265V AC\/DC 12V 24V 36V 48V<\/td><td>3000K-6500K<\/td><td>&gt;0.97<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-71139c7e\">\n<h2 class=\"wp-block-heading\">Luci stradali a prova di esplosione Potenza:<\/h2>\n\n\n\n<p>50W, 100W, 150W, 200W, 250W, 300W<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lampioni antideflagranti Certificato:<\/h2>\n\n\n\n<p><a href=\"http:\/\/www.iecex-certs.com\/\" rel=\"nofollow noopener\" target=\"_blank\">Certificato ATEX<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Luci stradali antideflagranti Caratteristiche:<\/h2>\n\n\n\n<p>\u00c8 realizzato in lega di alluminio ad alta resistenza contenente magnesio e titanio in quantit\u00e0 non superiore a 7,5%, che presenta un'eccellente resistenza agli urti e pu\u00f2 sopportare un impatto non inferiore a quello di un coltello.<\/p>\n\n\n\n<p>La lampada \u00e8 dotata di sorgenti luminose a LED di marchi internazionali. Emette luce in un'unica direzione, ha una luce morbida, una lunga durata ed \u00e8 ecologica.<\/p>\n\n\n\n<p>\u00c8 dotato di un dispositivo driver LED di marca, con ingresso ad ampia tensione, e dispone di funzioni quali corrente costante, protezione da circuito aperto, protezione da cortocircuito e protezione da sovratensione.<\/p>\n\n\n\n<p>La struttura di conduzione del calore della piastra di base in alluminio, appositamente progettata, \u00e8 strettamente collegata alla cavit\u00e0 della sorgente luminosa, in modo da garantire che il calore emesso dalla sorgente luminosa venga condotto completamente alle nervature di dissipazione del calore. Il flusso d'aria viene utilizzato per rimuovere efficacemente il calore generato dal funzionamento dei LED.<\/p>\n\n\n\n<p>La lente ha un design completamente chiuso e la lente morbida copre l'intera area. La struttura non \u00e8 soggetta ad allentarsi o a cadere.<\/p>\n\n\n\n<p>Gli elementi di fissaggio esposti sono in acciaio inox con elevate prestazioni anticorrosione.<\/p>\n\n\n\n<p>Il design scientifico della struttura di tenuta, le strisce di tenuta appositamente realizzate e il metodo di inserimento garantiscono eccellenti prestazioni di impermeabilit\u00e0 e antipolvere, consentendo l'utilizzo in ambienti difficili.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dettagli sui lampioni antideflagranti:<\/h2>\n\n\n\n<p>1<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-IP66.jpg\" alt=\"\" class=\"wp-image-4967\" title=\"\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-IP66.jpg 800w, https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-IP66-300x300.jpg 300w, https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-IP66-150x150.jpg 150w, https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-IP66-768x768.jpg 768w, https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-IP66-12x12.jpg 12w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Dimensioni e installazione dei lampioni antideflagranti:<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-0867b09d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-sizes.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-sizes.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-sizes.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-sizes.png\" alt=\"\" class=\"uag-image-4965\" width=\"300\" height=\"300\" title=\"Dimensioni dei lampioni antideflagranti\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-2c20e4ba wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-installation-1024x489.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-installation.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-installation.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2026\/01\/explosion-proof-street-lights-installation-1024x489.png\" alt=\"\" class=\"uag-image-4966\" width=\"300\" height=\"300\" title=\"Installazione di lampioni antideflagranti\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Applicazioni per i lampioni antideflagranti:<\/strong><\/h2>\n\n\n\n<p>Adatto per l'illuminazione generale o di emergenza in aree pericolose interne ed esterne dove sono presenti ambienti contenenti gas o vapori esplosivi delle categorie IIA, IIB e IIC, con gruppi di temperatura T1-T4; aree 1, 2 o zone 20, 21, 22 che contengono polveri esplosive o infiammabili.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Amasly Light FAQ<\/strong><\/h2>\n\n\n\n<p><strong>Q1.Can ho un ordine del campione per la luce principale?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: S\u00ec, accogliamo con favore l'ordine di campioni per testare e controllare la qualit\u00e0. I campioni misti sono accettabili.<\/p>\n\n\n\n<p><strong>Q2.E i tempi di consegna?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: Il campione ha bisogno di 3-5 giorni, la produzione di massa di 1-2 settimane.<\/p>\n\n\n\n<p><strong>Q3.Do you have any MOQ limit for led light order?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>A: Il basso MOQ 1pc per il controllo del campione \u00e8 disponibile.<\/p>\n\n\n\n<p><strong>Q4. Come spedite la merce e quanto tempo ci vuole per arrivare?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: Di solito spediamo tramite <a href=\"https:\/\/www.dhl.com\" rel=\"nofollow noopener\" target=\"_blank\">DHL<\/a>, UPS, FedEx o TNT. Il tempo di arrivo \u00e8 solitamente di 3-5 giorni. Linea aerea e spedizione via mare anche opzionale.<\/p>\n\n\n\n<p><strong>Q5. Come procedere per un ordine di luce a led?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>A:<\/p>\n\n\n\n<p>Innanzitutto fateci conoscere le vostre esigenze o la vostra applicazione.<\/p>\n\n\n\n<p>In secondo luogo, facciamo preventivi in base alle vostre esigenze o ai nostri suggerimenti.<\/p>\n\n\n\n<p>In terzo luogo, il cliente conferma i campioni e versa un deposito per l'ordine formale.<\/p>\n\n\n\n<p>In quarto luogo, organizziamo la produzione.<\/p>\n\n\n\n<p><strong>Q6.\u00c8 possibile stampare il mio <\/strong><strong>LOGO<\/strong><strong>&nbsp;sul prodotto luce a led?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>A: S\u00ec. Si prega di informarci formalmente prima della nostra produzione e di confermare il design in primo luogo sulla base del nostro campione.<\/p>\n\n\n\n<p><strong>Q7: Offrite una garanzia per i prodotti?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: S\u00ec, offriamo una garanzia di 2-5 anni sui nostri prodotti.<\/p>\n\n\n\n<p><strong>D8: Come comportarsi con il difettoso?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>A:<\/p>\n\n\n\n<p>In primo luogo, i nostri prodotti sono producono il sistema di controllo di qualit\u00e0 del dinstrict ed il tasso difettoso sar\u00e0 di meno che 0.2%<\/p>\n\n\n\n<p>In secondo luogo, durante il periodo di garanzia, forniremo parti di ricambio per sostituire il pezzo difettoso. Per gli ordini di grandi quantit\u00e0, forniremo in anticipo le parti vulnerabili, oppure potremo discutere soluzioni, tra cui il richiamo, in base alla situazione reale.<\/p>\n\n\n\n<p><strong>D9: Possiamo produrre lampade antideflagranti a bassa tensione con tensioni CA\/CC di 12V, 24V, 36V o 48V? <\/strong><\/p>\n\n\n\n<p>Amasly pu\u00f2 essere utilizzato come luce antideflagrante sia a bassa che ad alta tensione - AC\/DC 12V, 24V, 36V, 48V, AC 85-265V, AC 380V. <\/p>\n\n\n\n<p><strong>Q10: \u00c8 possibile aggiungere batterie di emergenza alle Explosion Poof Lights? <\/strong><\/p>\n\n\n\n<p>La lampada antideflagrante Amasly pu\u00f2 essere dotata di batterie di emergenza al litio. La durata dell'emergenza \u00e8 di 90 minuti, 120 minuti o 180 minuti. <\/p>\n\n\n\n<p><strong>Q11: La lampada antideflagrante Amasly pu\u00f2 essere personalizzata come prodotto OEM? <\/strong><\/p>\n\n\n\n<p>Le lampade antideflagranti Amasly possono essere personalizzate in base alle esigenze del cliente sia per le lampade che per i cartoni di imballaggio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prodotti correlati<\/h2>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-66e4defc alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a42945f9\">\n<div class=\"wp-block-uagb-image uagb-block-7296296b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/products\/explosion-proof-lights\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png\" alt=\"\" class=\"uag-image-1495\" width=\"300\" height=\"300\" title=\"Luci a baia antideflagranti\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4d3efde5\">\n<div class=\"wp-block-uagb-image uagb-block-c9e90797 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/products\/ex-proof-electrical-appliance\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg\" alt=\"Ex-Proof Electrical Appliance\" class=\"uag-image-1767\" width=\"300\" height=\"300\" title=\"Ventilatore a flusso assiale a prova di esplosione\" loading=\"lazy\" role=\"img\"\/><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-11c2578b\">\n<div class=\"wp-block-uagb-image uagb-block-6e8883aa wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/products\/explosion-proof-lights\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png\" alt=\"\" class=\"uag-image-1501\" width=\"300\" height=\"300\" title=\"Luce della stazione di servizio a prova di esplosione a LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-548945b5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-967755d5\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/products\/explosion-proof-lights\/\">Luci LED a prova di esplosione<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9bc52fc2\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/products\/ex-proof-electrical-appliance\/\">Apparecchio elettrico a prova di Ex<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8ffa0a23\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/products\/explosion-proof-lights\/\">Luci per stazioni di servizio a prova di esplosione<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-29499fe0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-777ee1c7\">\n<div class=\"wp-block-uagb-image uagb-block-2e9a1851 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/products\/led-flood-lights\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg\" alt=\"\" class=\"uag-image-1526\" width=\"300\" height=\"300\" title=\"50W 100W 150W 200W 300W Luce di inondazione LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-af8c8683\">\n<div class=\"wp-block-uagb-image uagb-block-67947854 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/products\/led-high-bay-light\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp\" alt=\"\" class=\"uag-image-3954\" width=\"300\" height=\"300\" title=\"luce ad alta intensit\u00e0\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0fdfdd58\">\n<div class=\"wp-block-uagb-image uagb-block-1187d32d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg\" alt=\"\" class=\"uag-image-1145\" width=\"300\" height=\"300\" title=\"Illuminazione stradale a LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6a60882c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-f1e91a35\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/products\/led-flood-lights\/\">Luci LED Flood<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-165bfa58\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/products\/led-high-bay-light\/\">Luci a LED per alta baia<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f6096e3b\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/products\/https:\/\/led.amasly.com\/products\/led-street-lights\/\">Luci stradali a LED<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-99c0e0a5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>BAY82 50W 100W 150W 200W 250W LED Explosion Proof Street Lights Content Contact Scope of application 1. widely used in oil mining, oil refining, chemical, military and other dangerous environmental places of the factory and road lighting 2. suitable for coastal, river and other wind pressure, wind speed environment; 3. suitable for thousands of explosive [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1156,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"[]"},"class_list":["post-4964","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/it\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"BAY82 50W 100W 150W 200W 250W LED Explosion Proof Street Lights Content Contact Scope of application 1. widely used in oil mining, oil refining, chemical, military and other dangerous environmental places of the factory and road lighting 2. suitable for coastal, river and other wind pressure, wind speed environment; 3. suitable for thousands of explosive&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages\/4964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/comments?post=4964"}],"version-history":[{"count":1,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages\/4964\/revisions"}],"predecessor-version":[{"id":4968,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages\/4964\/revisions\/4968"}],"up":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages\/1156"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/media?parent=4964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}