{"id":2407,"date":"2025-03-09T19:25:01","date_gmt":"2025-03-09T11:25:01","guid":{"rendered":"https:\/\/led.amasly.com\/?page_id=2407"},"modified":"2026-01-18T20:20:42","modified_gmt":"2026-01-18T12:20:42","slug":"campana-antideflagrante-2","status":"publish","type":"page","link":"https:\/\/led.amasly.com\/it\/prodotti\/apparecchio-elettrico-a-prova-di-ex\/campana-antideflagrante-2\/","title":{"rendered":"Campana antideflagrante"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e407eb08 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-7c0a134c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">Campana antideflagrante Allarme antideflagrante<\/h1>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-bell.jpg\" alt=\"Campana antideflagrante\" class=\"wp-image-1779\" title=\"\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-bell.jpg 300w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-bell-150x150.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption class=\"wp-element-caption\">Campana antideflagrante<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5d28ec94 default uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-462981e6\">\n<div class=\"wp-block-uagb-container uagb-block-6f08c8e4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-b229cb92\">\n<h3 class=\"wp-block-heading\">Contenuto<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-container-core-buttons-is-layout-d95c7545 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-antideflagranti\/\">Luci a prova di esplosione<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/apparecchio-elettrico-a-prova-di-ex\/\">Apparecchio elettrico a prova di Ex<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luce-triprova-a-led-2\/\">Luce a LED a prova di inciampo<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luce-a-led-ad-alta-baia\/\">Alta luce della baia a LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-di-inondazione-a-led\/\">Luce di inondazione a LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-stradali-a-led\/\">Illuminazione stradale a LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-solari\/\">Luce solare a LED<\/a><\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">Contatto<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Email: sales01@amasly.com<strong> <\/strong>      <\/li>\n\n\n\n<li>Mobile:<strong> <\/strong>+86 13732643699                   <\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-uagb-container uagb-block-064256a4\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<p class=\"wp-block-paragraph\">Quando si verifica un incidente o un incendio nel sito di produzione, il segnale di controllo inviato dalla centralina antincendio attiver\u00e0 il circuito di allarme e invier\u00e0 un segnale acustico per completare l'allarme. Pu\u00f2 anche essere utilizzato insieme al pulsante di allarme manuale per ottenere un semplice allarme sonoro. Struttura ragionevole, bella modellazione, prestazioni affidabili, facile da installare, \u00e8 un dispositivo di allarme antincendio altamente affidabile e con una forte capacit\u00e0 anti-interferenza.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Campana antideflagrante Caratteristiche del prodotto:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u25c6 Applicabile alle aree pericolose della Zona 1 e della Zona 2;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Applicabile alla classe IIA, IIB, gruppo di temperatura T1 ~ T4, ambiente con gas esplosivi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il guscio \u00e8 realizzato con una fusione in lega di alluminio e la superficie viene spruzzata ad alta pressione con un sistema elettrostatico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La superficie della campana \u00e8 rivestita di bronzo al berillio, che non produce scintille quando si batte;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Struttura compatta, bell'aspetto, facile installazione e manutenzione per gli utenti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u25c6 Tubi d'acciaio o cavi di cablaggio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Campana antideflagrante<\/strong> <strong>Parametri tecnici:<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Standard di esecuzione: IEC60079<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Simbolo antideflagrante: <a href=\"http:\/\/www.iecex-certs.com\/\" rel=\"nofollow noopener\" target=\"_blank\">Ex d IIB T6 Gb<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tensione nominale: AC: 220V, 110V, 36V<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">DC: 220V, 110V, 36V, 24V<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Potenza: \u2264 20W<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diametro del coperchio della campana: 125 mm<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Intensit\u00e0 a singolo effetto: \u226575dB<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grado di protezione: IP54<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grado di anticorrosione: WF1<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Specifica di ingresso: G3\/4<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Specifiche del cavo: \u03a69mm~\u03a614mm<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Amasly Light FAQ<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q1.Can ho un ordine del campione per la luce principale?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: S\u00ec, accogliamo con favore l'ordine di campioni per testare e controllare la qualit\u00e0. I campioni misti sono accettabili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q2.E i tempi di consegna?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: Il campione ha bisogno di 3-5 giorni, la produzione di massa di 1-2 settimane.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q3.Do you have any MOQ limit for led light order?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A: Il basso MOQ 1pc per il controllo del campione \u00e8 disponibile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q4. Come spedite la merce e quanto tempo ci vuole per arrivare?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: Di solito spediamo tramite <a href=\"https:\/\/www.dhl.com\" rel=\"nofollow noopener\" target=\"_blank\">DHL<\/a>, UPS, FedEx o TNT. Il tempo di arrivo \u00e8 solitamente di 3-5 giorni. Linea aerea e spedizione via mare anche opzionale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q5. Come procedere per un ordine di luce a led?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Innanzitutto fateci conoscere le vostre esigenze o la vostra applicazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In secondo luogo, facciamo preventivi in base alle vostre esigenze o ai nostri suggerimenti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In terzo luogo, il cliente conferma i campioni e versa un deposito per l'ordine formale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In quarto luogo, organizziamo la produzione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q6.\u00c8 possibile stampare il mio <\/strong><strong>LOGO<\/strong><strong>&nbsp;sul prodotto luce a led?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A: S\u00ec. Si prega di informarci formalmente prima della nostra produzione e di confermare il design in primo luogo sulla base del nostro campione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q7: Offrite una garanzia per i prodotti?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R: S\u00ec, offriamo una garanzia di 2-5 anni sui nostri prodotti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D8: Come comportarsi con il difettoso?<\/strong><strong><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In primo luogo, i nostri prodotti sono producono il sistema di controllo di qualit\u00e0 del dinstrict ed il tasso difettoso sar\u00e0 di meno che 0.2%<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In secondo luogo, durante il periodo di garanzia, forniremo parti di ricambio per sostituire il pezzo difettoso. Per gli ordini di grandi quantit\u00e0, forniremo in anticipo le parti vulnerabili, oppure potremo discutere soluzioni, tra cui il richiamo, in base alla situazione reale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>D9: Possiamo produrre lampade antideflagranti a bassa tensione con tensioni CA\/CC di 12V, 24V, 36V o 48V? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amasly pu\u00f2 essere utilizzato come luce antideflagrante sia a bassa che ad alta tensione - AC\/DC 12V, 24V, 36V, 48V, AC 85-265V, AC 380V. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q10: \u00c8 possibile aggiungere batterie di emergenza alle Explosion Poof Lights? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lampada antideflagrante Amasly pu\u00f2 essere dotata di batterie di emergenza al litio. La durata dell'emergenza \u00e8 di 90 minuti, 120 minuti o 180 minuti. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Q11: La lampada antideflagrante Amasly pu\u00f2 essere personalizzata come prodotto OEM? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le lampade antideflagranti Amasly possono essere personalizzate in base alle esigenze del cliente sia per le lampade che per i cartoni di imballaggio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prodotti correlati<\/h2>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-66e4defc alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a42945f9\">\n<div class=\"wp-block-uagb-image uagb-block-7296296b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-antideflagranti\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png\" alt=\"\" class=\"uag-image-1495\" width=\"300\" height=\"300\" title=\"Luci a baia antideflagranti\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4d3efde5\">\n<div class=\"wp-block-uagb-image uagb-block-c9e90797 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/apparecchio-elettrico-a-prova-di-ex\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg\" alt=\"Apparecchio elettrico a prova di Ex\" class=\"uag-image-1767\" width=\"300\" height=\"300\" title=\"Ventilatore a flusso assiale a prova di esplosione\" loading=\"lazy\" role=\"img\" \/><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-11c2578b\">\n<div class=\"wp-block-uagb-image uagb-block-6e8883aa wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-antideflagranti\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png\" alt=\"\" class=\"uag-image-1501\" width=\"300\" height=\"300\" title=\"Luce della stazione di servizio a prova di esplosione a LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-548945b5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-967755d5\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-antideflagranti\/\">Luci LED a prova di esplosione<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9bc52fc2\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/prodotti\/apparecchio-elettrico-a-prova-di-ex\/\">Apparecchio elettrico a prova di Ex<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8ffa0a23\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-antideflagranti\/\">Luci per stazioni di servizio a prova di esplosione<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-29499fe0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-777ee1c7\">\n<div class=\"wp-block-uagb-image uagb-block-2e9a1851 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-di-inondazione-a-led\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg\" alt=\"\" class=\"uag-image-1526\" width=\"300\" height=\"300\" title=\"50W 100W 150W 200W 300W Luce di inondazione LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-af8c8683\">\n<div class=\"wp-block-uagb-image uagb-block-67947854 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/luce-a-led-ad-alta-baia\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp\" alt=\"\" class=\"uag-image-3954\" width=\"300\" height=\"300\" title=\"luce ad alta intensit\u00e0\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0fdfdd58\">\n<div class=\"wp-block-uagb-image uagb-block-1187d32d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/it\/prodotti\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg\" alt=\"\" class=\"uag-image-1145\" width=\"300\" height=\"300\" title=\"Illuminazione stradale a LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6a60882c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-f1e91a35\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/prodotti\/luci-di-inondazione-a-led\/\">Luci LED Flood<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-165bfa58\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/prodotti\/luce-a-led-ad-alta-baia\/\">Luci a LED per alta baia<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f6096e3b\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/it\/prodotti\/https%3a\/\/led.amasly.com\/prodotti\/luci-stradali-a-led\/\">Luci stradali a LED<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-99c0e0a5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Explosion Proof bell Explosion Proof Alarm Content Contact When an accident or fire occurs in the production site, the control signal sent by the fire alarm controller will activate the alarm circuit and send out an acoustic alarm signal to complete the alarm purpose. It can also be used together with manual alarm button to [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1168,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"[]"},"class_list":["post-2407","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/it\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"Explosion Proof bell Explosion Proof Alarm Content Contact When an accident or fire occurs in the production site, the control signal sent by the fire alarm controller will activate the alarm circuit and send out an acoustic alarm signal to complete the alarm purpose. It can also be used together with manual alarm button to&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages\/2407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/comments?post=2407"}],"version-history":[{"count":2,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages\/2407\/revisions"}],"predecessor-version":[{"id":4532,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages\/2407\/revisions\/4532"}],"up":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/pages\/1168"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/it\/wp-json\/wp\/v2\/media?parent=2407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}