{"id":1173,"date":"2024-07-16T17:50:48","date_gmt":"2024-07-16T09:50:48","guid":{"rendered":"https:\/\/led.amasly.com\/?page_id=1173"},"modified":"2026-04-20T21:51:11","modified_gmt":"2026-04-20T13:51:11","slug":"led-high-bay-light","status":"publish","type":"page","link":"https:\/\/led.amasly.com\/es_mx\/products\/led-high-bay-light\/","title":{"rendered":"Luz LED para techos altos"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e407eb08 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-7c0a134c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">Industrial LED High Bay Light for Warehouse &amp; Factory<\/h1>\n\n\n\n<p>Las High Bay Lights, tambi\u00e9n conocidas como canopy Lights, son luminarias LED de bajo consumo para interiores.<\/p>\n\n\n\n<p>Amasly ofrece diferentes tipos de luces de alta bah\u00eda y luces de baja bah\u00eda: UFO de alta bah\u00eda, lineal de alta bah\u00eda, la plaza de alta bah\u00eda.<\/p>\n\n\n\n<p>La potencia oscila entre 50 W y 1.000 W.<\/p>\n\n\n\n<p>Voltaje: AC85V-480V<\/p>\n\n\n\n<p>Eficacia luminosa: 120lm\/w-200lm\/w.<\/p>\n\n\n\n<p>Los principales lugares de aplicaci\u00f3n de las luces de gran altura incluyen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Plantas industriales: mecanizado, fabricaci\u00f3n electr\u00f3nica, reparaci\u00f3n de autom\u00f3viles y otros tipos de l\u00edneas de producci\u00f3n industrial, necesitan un entorno de iluminaci\u00f3n brillante y estable para garantizar que los trabajadores puedan ver claramente el \u00e1rea de trabajo, mejorar la eficiencia y la seguridad laboral.<\/li>\n\n\n\n<li>Minas: En las minas, las condiciones de iluminaci\u00f3n son especialmente importantes, ya que los entornos oscuros pueden aumentar el riesgo de accidentes. Las luces de gran altura pueden proporcionar suficiente luminosidad para ayudar a los mineros a mantener una visi\u00f3n clara cuando trabajan bajo tierra.<\/li>\n\n\n\n<li>Almacenes y centros log\u00edsticos: Los almacenes y centros log\u00edsticos suelen requerir una iluminaci\u00f3n amplia y de alta intensidad para que el personal pueda localizar y mover las mercanc\u00edas con precisi\u00f3n. Las l\u00e1mparas de gran altura son ideales para estos lugares porque pueden proporcionar una iluminaci\u00f3n uniforme y brillante.<\/li>\n\n\n\n<li>Grandes locales comerciales: estadios, salas de exposiciones, grandes centros comerciales y otros lugares con mucho espacio tambi\u00e9n necesitan l\u00e1mparas de gran altura para proporcionar una iluminaci\u00f3n adecuada. Estos lugares suelen tener espacios abiertos y techos altos, por lo que necesitan l\u00e1mparas con un amplio rango de irradiaci\u00f3n.<\/li>\n\n\n\n<li>Otros entornos industriales: laboratorios, centros de investigaci\u00f3n y desarrollo, zonas de producci\u00f3n qu\u00edmica y otros lugares que requieren una iluminaci\u00f3n precisa y un buen entorno de trabajo tambi\u00e9n pueden utilizar l\u00e1mparas de gran altura para satisfacer sus necesidades de iluminaci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6f08c8e4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-b229cb92\">\n<h3 class=\"wp-block-heading\">Contenido<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-container-core-buttons-is-layout-45b20515 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/explosion-proof-lights\/\">Luces antideflagrantes<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/ex-proof-electrical-appliance\/\">Aparato el\u00e9ctrico a prueba de explosiones<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-tri-proof-light-2\/\">Luz LED a prueba de tropiezos<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-high-bay-light\/\">Luz LED para techos altos<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-flood-lights\/\">Proyectores LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-street-lights\/\">Farolas LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/solar-lights\/\">Luz solar LED<\/a><\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">P\u00f3ngase en contacto con<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Email:sales01@amasly.com <strong>       <\/strong><\/li>\n\n\n\n<li>M\u00f3vil: +86 13732643699                   <\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6c5ab58c\">\n<div class=\"wp-block-uagb-image uagb-block-4fa1bf04 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/high-bay-light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/high-bay-light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/high-bay-light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/high-bay-light.jpg\" alt=\"LED High Bay Light\" class=\"uag-image-1134\" width=\"300\" height=\"300\" title=\"high-bay-light\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f0c73b09\">\n<div class=\"wp-block-uagb-image uagb-block-d13169ed wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/high-bay-lights.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/high-bay-lights.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/high-bay-lights.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/high-bay-lights.png\" alt=\"\" class=\"uag-image-4349\" width=\"300\" height=\"300\" title=\"luces de gran altura\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-b42f9230 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/highbay-lights.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/highbay-lights.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/highbay-lights.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/highbay-lights.jpg\" alt=\"\" class=\"uag-image-4344\" width=\"300\" height=\"300\" title=\"luces de bah\u00eda alta\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-ab565980 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/100W-high-bay-lights.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/100W-high-bay-lights.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/100W-high-bay-lights.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/100W-high-bay-lights.jpg\" alt=\"\" class=\"uag-image-4346\" width=\"300\" height=\"300\" title=\"Luces de gran altura de 100 W\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-a45053e6 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/08\/LED-Linear-High-Bay-Lights.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/08\/LED-Linear-High-Bay-Lights.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/08\/LED-Linear-High-Bay-Lights.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/08\/LED-Linear-High-Bay-Lights.jpg\" alt=\"\" class=\"uag-image-1479\" width=\"300\" height=\"300\" title=\"Luces LED lineales de gran altura\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d44a74cf\">\n<div class=\"wp-block-uagb-image uagb-block-61a2029c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-high-bay-light\/hbs1\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-high-bay-light2.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-high-bay-light2.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-high-bay-light2.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-high-bay-light2.jpg\" alt=\"\" class=\"uag-image-1136\" width=\"300\" height=\"300\" title=\"led-alta-bah\u00eda-luz2\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a8824bc4\">\n<div class=\"wp-block-uagb-image uagb-block-f66f71a3 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-LED-Lights.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-LED-Lights.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-LED-Lights.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-LED-Lights.jpg\" alt=\"\" class=\"uag-image-4342\" width=\"300\" height=\"300\" title=\"Luces LED OVNI\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-bb1fdeca wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/LED-high-bay-lights.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/LED-high-bay-lights.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/LED-high-bay-lights.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/LED-high-bay-lights.png\" alt=\"\" class=\"uag-image-4345\" width=\"300\" height=\"300\" title=\"Luces LED de gran altura\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-36652182 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/high-bay-lights-100W-150W-200W.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/high-bay-lights-100W-150W-200W.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/high-bay-lights-100W-150W-200W.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/high-bay-lights-100W-150W-200W.jpg\" alt=\"\" class=\"uag-image-4347\" width=\"300\" height=\"300\" title=\"luces de gran altura 100W 150W 200W\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-49660caa wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/\u7a7a\u767d.bmp ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/\u7a7a\u767d.bmp 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/\u7a7a\u767d.bmp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/\u7a7a\u767d.bmp\" alt=\"\" class=\"uag-image-1263\" width=\"300\" height=\"300\" title=\"\u7a7a\u767d\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ceb98619\">\n<div class=\"wp-block-uagb-container uagb-block-224937b1\">\n<div class=\"wp-block-uagb-image uagb-block-1efb87dd wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-high-bay.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-high-bay.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-high-bay.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-high-bay.jpg\" alt=\"UFO high bay\" class=\"uag-image-4338\" width=\"300\" height=\"300\" title=\"OVNI de gran altura\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-c5026e55 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-high-bay-lights.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-high-bay-lights.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-high-bay-lights.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/UFO-high-bay-lights.jpg\" alt=\"\" class=\"uag-image-4343\" width=\"300\" height=\"300\" title=\"Luces OVNI de gran altura\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-0d85b98a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-high-bay-light\/hbl2\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-Linear-high-bay-lights.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-Linear-high-bay-lights.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-Linear-high-bay-lights.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-Linear-high-bay-lights.jpg\" alt=\"\" class=\"uag-image-1322\" width=\"300\" height=\"300\" title=\"Luces LED lineales de gran altura\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-71e8568b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/LED-highbay-lights.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/LED-highbay-lights.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/LED-highbay-lights.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/11\/LED-highbay-lights.jpg\" alt=\"\" class=\"uag-image-4348\" width=\"300\" height=\"300\" title=\"Luces LED de techo\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-59a875a1 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-high-bay-light\/hbl2\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-Linear-high-bay-lights.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-Linear-high-bay-lights.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-Linear-high-bay-lights.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-Linear-high-bay-lights.jpg\" alt=\"\" class=\"uag-image-1322\" width=\"300\" height=\"300\" title=\"Luces LED lineales de gran altura\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Par\u00e1metros de la luminaria LED para techos altos Amasly UFO:<\/strong><\/h2>\n\n\n\n<p>Amasly ofrece luces LED de gran altura que van desde 50W a 500W.<\/p>\n\n\n\n<p>Potencia: 50W 100W 150W 200W 250W 300W 400W 500W<\/p>\n\n\n\n<p>CCT: 2700-6500K<\/p>\n\n\n\n<p>CRI: &gt;80<\/p>\n\n\n\n<p>Voltaje: AC85-265V, AC 380V, AC480V (Opcional)<\/p>\n\n\n\n<p>Gama de frecuencias: 50\/60HZ<\/p>\n\n\n\n<p>Sensores: sensor de luz diurna y sensor de movimiento (sensor de microondas), sensor de infrarrojos.<\/p>\n\n\n\n<p>Regulable: Regulaci\u00f3n 0-10V, Regulaci\u00f3n Zigbee, Regulaci\u00f3n Dali<\/p>\n\n\n\n<p>\u00c1ngulo del haz: 30\u00b060\u00b0 90\u00b0 120<\/p>\n\n\n\n<p>Grado de protecci\u00f3n IP: IP66<\/p>\n\n\n\n<p>Emergencia: 90min, 120min, 180min (Opcional)<\/p>\n\n\n\n<p>Factor de potencia: &gt;0.9<\/p>\n\n\n\n<p>Eficacia luminosa: 120lm\/w 150lm\/w 180lm\/w 200lm\/w<\/p>\n\n\n\n<p>Vida \u00fatil: 50000hrs<\/p>\n\n\n\n<p>Garant\u00eda: 3 y 5 a\u00f1os<\/p>\n\n\n\n<p>UGR\u226419<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Preguntas frecuentes sobre Amasly Light<\/strong><\/h2>\n\n\n\n<p><strong>P1.\u00bfPuedo recibir un pedido de muestra de luz led?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: S\u00ed, aceptamos pedidos de muestras para probar y comprobar la calidad. Las muestras mezcladas son aceptables.<\/p>\n\n\n\n<p><strong>P2: \u00bfY el plazo de entrega?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: La muestra necesita 3-5 d\u00edas, el tiempo de producci\u00f3n en masa necesita 1-2 semanas.<\/p>\n\n\n\n<p><strong>Q3.Do usted tiene cualquier l\u00edmite MOQ para la luz led orden?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: Bajo MOQ 1pc para la comprobaci\u00f3n de la muestra est\u00e1 disponible.<\/p>\n\n\n\n<p><strong>Q4. \u00bfC\u00f3mo env\u00edan la mercanc\u00eda y cu\u00e1nto tarda en llegar?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: Normalmente enviamos por <a href=\"https:\/\/www.dhl.com\" rel=\"nofollow noopener\" target=\"_blank\">DHL<\/a>, UPS, FedEx o TNT. El env\u00edo suele tardar entre 3 y 5 d\u00edas en llegar. Tambi\u00e9n se ofrece la opci\u00f3n de env\u00edo a\u00e9reo y mar\u00edtimo.<\/p>\n\n\n\n<p><strong>Q5. \u00bfC\u00f3mo tramitar un pedido de luz led?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>A:<\/p>\n\n\n\n<p>En primer lugar, comun\u00edquenos sus necesidades o su solicitud.<\/p>\n\n\n\n<p>En segundo lugar, presupuestamos seg\u00fan sus requisitos o nuestras sugerencias.<\/p>\n\n\n\n<p>En tercer lugar, el cliente confirma las muestras y realiza el dep\u00f3sito para el pedido formal.<\/p>\n\n\n\n<p>En cuarto lugar, organizamos la producci\u00f3n.<\/p>\n\n\n\n<p><strong>P6.\u00bfPuedo imprimir mi <\/strong><strong>LOGO<\/strong><strong>&nbsp;en producto de luz led ?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: S\u00ed, por favor inf\u00f3rmenos formalmente antes de nuestra producci\u00f3n y confirmar el dise\u00f1o en primer lugar sobre la base de nuestra muestra.<\/p>\n\n\n\n<p><strong>P7: \u00bfOfrecen garant\u00eda para los productos?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: S\u00ed, ofrecemos de 2 a 5 a\u00f1os de garant\u00eda para nuestros productos.<\/p>\n\n\n\n<p><strong>P8: \u00bfC\u00f3mo tratar los fallos?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>A:<\/p>\n\n\n\n<p>En primer lugar, nuestros productos se producen dinstrict sistema de control de calidad y la tasa de defectos ser\u00e1 inferior a 0,2%<\/p>\n\n\n\n<p>En segundo lugar, durante el per\u00edodo de garant\u00eda, proporcionaremos piezas para sustituir la pieza defectuosa.. Para los pedidos al por mayor, proporcionaremos piezas vulnerables por adelantado, o podemos discutir soluciones, incluyendo la retirada del mercado sobre la base de la situaci\u00f3n real.<\/p>\n\n\n\n<p><strong>P9: \u00bfPodemos fabricar l\u00e1mparas antideflagrantes de bajo voltaje con voltajes CA\/CC de 12 V, 24 V, 36 V o 48 V? <\/strong><\/p>\n\n\n\n<p>Amasly se puede utilizar como luminaria antideflagrante tanto de baja como de alta tensi\u00f3n: CA\/CC 12 V, 24 V, 36 V, 48 V, CA 85-265 V, CA 380 V. <\/p>\n\n\n\n<p><strong>P10: \u00bfSe pueden a\u00f1adir bater\u00edas de emergencia Explosion Poof Lights? <\/strong><\/p>\n\n\n\n<p>La l\u00e1mpara a prueba de explosiones Amasly puede equiparse con bater\u00edas de litio de emergencia. La duraci\u00f3n de la emergencia es de 90 minutos, 120 minutos o 180 minutos. <\/p>\n\n\n\n<p><strong>P11: \u00bfSe puede personalizar la l\u00e1mpara a prueba de explosiones Amasly como producto OEM? <\/strong><\/p>\n\n\n\n<p>Las l\u00e1mparas a prueba de explosiones de Amasly se pueden personalizar seg\u00fan los requisitos del cliente, tanto en lo que respecta a las l\u00e1mparas como a las cajas de embalaje.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Productos relacionados<\/h2>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-66e4defc alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a42945f9\">\n<div class=\"wp-block-uagb-image uagb-block-7296296b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/explosion-proof-lights\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png\" alt=\"\" class=\"uag-image-1495\" width=\"300\" height=\"300\" title=\"Luces de gran altura a prueba de explosiones\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4d3efde5\">\n<div class=\"wp-block-uagb-image uagb-block-c9e90797 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/ex-proof-electrical-appliance\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg\" alt=\"Ex-Proof Electrical Appliance\" class=\"uag-image-1767\" width=\"300\" height=\"300\" title=\"Ventilador axial antideflagrante\" loading=\"lazy\" role=\"img\"\/><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-11c2578b\">\n<div class=\"wp-block-uagb-image uagb-block-6e8883aa wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/explosion-proof-lights\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png\" alt=\"\" class=\"uag-image-1501\" width=\"300\" height=\"300\" title=\"L\u00e1mpara LED antideflagrante para gasolineras\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-548945b5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-967755d5\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es_mx\/products\/explosion-proof-lights\/\">Luces LED antideflagrantes<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9bc52fc2\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es_mx\/products\/ex-proof-electrical-appliance\/\">Aparato el\u00e9ctrico Ex-Proof<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8ffa0a23\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es_mx\/products\/explosion-proof-lights\/\">Luces de gasolinera a prueba de explosiones<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-29499fe0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-777ee1c7\">\n<div class=\"wp-block-uagb-image uagb-block-2e9a1851 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-flood-lights\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg\" alt=\"\" class=\"uag-image-1526\" width=\"300\" height=\"300\" title=\"L\u00e1mpara de inundaci\u00f3n LED 50W 100W 150W 200W 300W\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-af8c8683\">\n<div class=\"wp-block-uagb-image uagb-block-67947854 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-high-bay-light\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp\" alt=\"\" class=\"uag-image-3954\" width=\"300\" height=\"300\" title=\"luz de gran altura\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0fdfdd58\">\n<div class=\"wp-block-uagb-image uagb-block-1187d32d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es_mx\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg\" alt=\"\" class=\"uag-image-1145\" width=\"300\" height=\"300\" title=\"Alumbrado p\u00fablico LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6a60882c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-f1e91a35\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-flood-lights\/\">Proyectores LED<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-165bfa58\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es_mx\/products\/led-high-bay-light\/\">Luces LED High Bay<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f6096e3b\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es_mx\/products\/https:\/\/led.amasly.com\/products\/led-street-lights\/\">Alumbrado p\u00fablico LED<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-99c0e0a5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Industrial LED High Bay Light for Warehouse &amp; Factory High Bay Lights, also known as canopy Lights, are energy efficient indoor LED luminaires. Amasly provides different types of high bay lights and low bay lights: UFO high bay, Linear high bay, Square high bay. The power ranges from 50W to 1000W. Voltage: AC85V-480V Light efficiency: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1039,"menu_order":4,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"[]"},"class_list":["post-1173","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/es_mx\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"Industrial LED High Bay Light for Warehouse &amp; Factory High Bay Lights, also known as canopy Lights, are energy efficient indoor LED luminaires. Amasly provides different types of high bay lights and low bay lights: UFO high bay, Linear high bay, Square high bay. The power ranges from 50W to 1000W. Voltage: AC85V-480V Light efficiency:&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/es_mx\/wp-json\/wp\/v2\/pages\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/es_mx\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/led.amasly.com\/es_mx\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es_mx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es_mx\/wp-json\/wp\/v2\/comments?post=1173"}],"version-history":[{"count":19,"href":"https:\/\/led.amasly.com\/es_mx\/wp-json\/wp\/v2\/pages\/1173\/revisions"}],"predecessor-version":[{"id":5042,"href":"https:\/\/led.amasly.com\/es_mx\/wp-json\/wp\/v2\/pages\/1173\/revisions\/5042"}],"up":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es_mx\/wp-json\/wp\/v2\/pages\/1039"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/es_mx\/wp-json\/wp\/v2\/media?parent=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}