{"id":2232,"date":"2025-03-04T21:06:45","date_gmt":"2025-03-04T13:06:45","guid":{"rendered":"https:\/\/led.amasly.com\/?p=2232"},"modified":"2025-03-06T22:37:20","modified_gmt":"2025-03-06T14:37:20","slug":"led-explosion-proof-lamps-and-lanterns-design-and-manufacturing","status":"publish","type":"post","link":"https:\/\/led.amasly.com\/es\/light\/led-explosion-proof-lamps-and-lanterns-design-and-manufacturing\/","title":{"rendered":"Dise\u00f1o y fabricaci\u00f3n de l\u00e1mparas y linternas LED antideflagrantes"},"content":{"rendered":"<h1 class=\"wp-block-heading\"><strong>Dise\u00f1o y fabricaci\u00f3n de l\u00e1mparas y linternas LED antideflagrantes<\/strong><strong><\/strong><\/h1>\n\n\n\n<p>Los equipos el\u00e9ctricos utilizados en ambientes explosivos se dividen en Clase I, Clase II y Clase III. Las l\u00e1mparas LED a prueba de explosiones de Clase II y Clase III no mineras se utilizan principalmente en industrias en las que existen gases o polvos inflamables y explosivos, como la petrolera, petroqu\u00edmica, qu\u00edmica, farmac\u00e9utica, etc. De acuerdo con el an\u00e1lisis de los equipos el\u00e9ctricos a prueba de explosiones, el uso principal de la prueba de explosiones, el aumento de la seguridad y el tipo compuesto. En la actualidad, el tipo a prueba de explosiones es la corriente principal de accesorios de iluminaci\u00f3n. En este art\u00edculo se analizan las opiniones y conclusiones del proceso de dise\u00f1o y fabricaci\u00f3n de productos de iluminaci\u00f3n LED a prueba de explosiones.<\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-7443a5c3 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u724717-1.png 800w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u724717-1-300x180.png 300w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u724717-1-768x460.png 768w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/03\/\u56fe\u724717-1.png\" alt=\"\" class=\"uag-image-2233\" width=\"800\" height=\"479\" title=\"\u56fe\u72471(7)\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>I. Caracter\u00edsticas de rendimiento de los LED<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;En primer lugar, el ahorro de energ\u00eda. Las l\u00e1mparas y linternas LED tienen una tensi\u00f3n de funcionamiento baja con un accionamiento de corriente constante. En el mismo efecto de iluminaci\u00f3n, el consumo de energ\u00eda es incandescente 1\/10, fluorescente 1\/2. Los entornos industriales a menudo requieren iluminaci\u00f3n a largo plazo, el efecto de ahorro de energ\u00eda es m\u00e1s significativo.<\/p>\n\n\n\n<p>En segundo lugar, la protecci\u00f3n del medio ambiente, el LED es un cuerpo emisor de luz duradera, resistencia al impacto, irrompible, residuos reciclables, sin contaminaci\u00f3n. La fuente de luz es peque\u00f1a, se puede combinar a voluntad, es un producto de iluminaci\u00f3n compacto f\u00e1cil de desarrollar, f\u00e1cil de instalar y mantener. Fuente de luz LED es actualmente m\u00e1s caro que las fuentes de luz convencionales, pero desde la perspectiva del ahorro de energ\u00eda, con un a\u00f1o de ahorro de energ\u00eda para recuperar la inversi\u00f3n en fuentes de luz, puede producir ahorro de energ\u00eda valor neto de varias veces el beneficio.<\/p>\n\n\n\n<p>De nuevo, alta eficiencia luminosa. LED despu\u00e9s de d\u00e9cadas de desarrollo, la eficiencia luminosa ha mejorado mucho. Fuente de luz convencional eficacia luminosa de 12-24 lm \/ W, l\u00e1mparas fluorescentes 50-70 lm \/ W, l\u00e1mparas de sodio 90-140 lm \/ W, la mayor parte del consumo de energ\u00eda es la p\u00e9rdida de calor. Eficacia luminosa LED mejorada de 80-200 lm \/ W, buena monocromaticidad \u00f3ptica, espectro estrecho, puede emitir directamente luz visible coloreada sin filtrar.<\/p>\n\n\n\n<p>Por \u00faltimo, larga vida \u00fatil. El uso de luminiscencia de radiaci\u00f3n de campo de luz electr\u00f3nica, luminiscencia de filamento es f\u00e1cil de quemar, evaporaci\u00f3n t\u00e9rmica, atenuaci\u00f3n de la luz, etc. Las luces LED son peque\u00f1as, ligeras, encapsuladas en resina epoxi, pueden soportar golpes mec\u00e1nicos de alta intensidad y vibraciones, y no es f\u00e1cil que se da\u00f1en. La esperanza de vida media de 100.000 horas. la vida \u00fatil de las l\u00e1mparas y linternas LED puede ser de hasta 5 a 10 a\u00f1os, lo que reduce en gran medida el coste de mantenimiento de l\u00e1mparas y linternas, para evitar el problema de la sustituci\u00f3n frecuente de l\u00e1mparas y linternas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>II. L\u00e1mpara LED antideflagrante a prueba de explosiones principio antideflagrante<\/strong><strong><\/strong><\/h2>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;A prueba de explosiones LED l\u00e1mpara a prueba de explosiones es la fuente de luz, fuente de alimentaci\u00f3n y otros componentes que pueden encender los gases explosivos est\u00e1n encerrados en una c\u00e1scara, en caso de una explosi\u00f3n, la c\u00e1scara puede soportar cualquier articulaciones o huecos estructurales a trav\u00e9s de la c\u00e1scara en la c\u00e1scara de la mezcla explosiva dentro de la explosi\u00f3n interna sin da\u00f1os, y no causar\u00e1 la formaci\u00f3n externa de un gas explosivo por una variedad de gases para encender el ambiente de gas explosivo, a fin de lograr el prop\u00f3sito de a prueba de explosiones. prop\u00f3sito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>III<\/strong><strong>. Dise\u00f1o y fabricaci\u00f3n de l\u00e1mparas y linternas LED antideflagrantes<\/strong><strong><\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3.1 estructura del producto<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;La c\u00e1scara de la l\u00e1mpara debe ser capaz de soportar el impacto de la explosi\u00f3n interna, de acuerdo con la combinaci\u00f3n de disipaci\u00f3n de calor y rentable, la c\u00e1scara se hace generalmente de fundici\u00f3n de aleaci\u00f3n de metal ligero (ZL102), las juntas a prueba de explosiones son a menudo roscadas, planas, cil\u00edndricas y otras formas; la rugosidad de la superficie a prueba de explosiones no se permite que sea superior a 6,3 \u03bcm, y la longitud de sus juntas a prueba de explosiones y el tama\u00f1o del volumen interno de la cavidad a prueba de explosiones y la brecha a prueba de explosiones est\u00e1 estrechamente relacionada.<\/p>\n\n\n\n<p>Las l\u00e1mparas antideflagrantes suelen estar compuestas por la cavidad de la fuente de luz, la cavidad de la fuente de alimentaci\u00f3n y la cavidad del cableado.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;La cavidad de la fuente de luz incluye la carcasa, la fuente de luz, la cubierta transparente, el reflector, etc. La cavidad de la fuente de luz es la parte de luz de toda la l\u00e1mpara, pero tambi\u00e9n la parte clave del calor generado, por lo que la cavidad de la fuente de luz, adem\u00e1s de un cierto grado de fuerza, tambi\u00e9n debe tener una buena funci\u00f3n de disipaci\u00f3n de calor, de modo que la temperatura de las l\u00e1mparas y linternas para cumplir con los requisitos del grupo de temperatura correspondiente. Cubierta transparente se hace generalmente de vidrio templado, la forma m\u00e1s com\u00fan es sellar la cubierta transparente con resina epoxi en la c\u00e1scara de la cavidad de la fuente de luz, y el uso del anillo de presi\u00f3n fija para lograr el efecto de a prueba de explosiones.<\/p>\n\n\n\n<p>La cavidad de la fuente de alimentaci\u00f3n incluye la carcasa, la fuente de alimentaci\u00f3n motriz y los terminales de cableado.<\/p>\n\n\n\n<p>Cavidad de cableado es la cavidad de las l\u00e1mparas y linternas y la interacci\u00f3n externa, su atenci\u00f3n se centra en el dise\u00f1o y uso del dispositivo de introducci\u00f3n. Dispositivo de introducci\u00f3n de cable para el m\u00e1s com\u00fanmente utilizado en la introducci\u00f3n de l\u00e1mparas a prueba de explosiones y linternas, el m\u00e1s com\u00fan es el uso de la introducci\u00f3n del anillo de sellado y la introducci\u00f3n de sello de embalaje. La introducci\u00f3n de la forma de sellado del dispositivo debe coincidir con el tama\u00f1o del anillo de sellado del cable, y con el tornillo de compresi\u00f3n totalmente comprimido para garantizar el rendimiento a prueba de explosiones de equipos el\u00e9ctricos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3.2 Dise\u00f1o de la fuente de alimentaci\u00f3n<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;Seg\u00fan la fuente de alimentaci\u00f3n de la fuente de luz LED, suele haber dos soluciones, una fuente de alimentaci\u00f3n multigrupo para proporcionar m\u00faltiples fuentes de corriente constante, cada fuente de corriente constante individualmente para cada fuente de alimentaci\u00f3n LED, estas combinaciones son flexibles. El fallo de un LED no afectar\u00e1 al funcionamiento de los dem\u00e1s LED. La otra, una fuente de alimentaci\u00f3n de corriente constante todo en uno, carece de flexibilidad, lo que significa que el fallo de un LED afectar\u00e1 al funcionamiento de otro. Desde el punto de vista del sistema, basado en los principios de fiabilidad y an\u00e1lisis, no se recomienda una simple conexi\u00f3n serie-paralelo entre componentes. Teniendo en cuenta el impacto de los factores relevantes, la consideraci\u00f3n primordial es hacer un uso completo de los componentes para mejorar plenamente la utilizaci\u00f3n de toda la fuente de luz. Por lo tanto, las soluciones de fuente de alimentaci\u00f3n centralizada de CC basadas en m\u00faltiples modos de corriente constante y las soluciones de fuente de alimentaci\u00f3n centralizada de CC de alto voltaje han recibido una amplia atenci\u00f3n. La fuente de alimentaci\u00f3n centralizada de CC se caracteriza por la alta fiabilidad del sistema, la alta eficiencia y el bajo coste. El dise\u00f1o sistem\u00e1tico, modular e inteligente mejora en gran medida la facilidad de uso y mantenimiento del sistema, y reduce significativamente los costes de gesti\u00f3n y mantenimiento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3.3 Dise\u00f1o de la fuente luminosa<\/strong><strong><\/strong><\/h3>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;Seg\u00fan la clasificaci\u00f3n de los materiales emisores de luz, la fuente de luz se divide en dos categor\u00edas: fuente de luz de estado s\u00f3lido y fuente de luz de descarga de gas. En los \u00faltimos a\u00f1os, con el r\u00e1pido desarrollo de la ciencia y la tecnolog\u00eda, el desarrollo del diodo emisor de luz semiconductor (LED) es r\u00e1pido. La fuente de luz LED se utiliza en la industria y la miner\u00eda, escuelas, hospitales, carreteras y otros tipos de iluminaci\u00f3n interior y exterior en diversos campos. En el an\u00e1lisis del principio de emisi\u00f3n de luz, fuente de luz de descarga de gas en el uso de una variedad de gases inertes para regular el rendimiento de la luz de la fuente de luz, tales como el flujo luminoso, temperatura de color, reproducci\u00f3n crom\u00e1tica y as\u00ed sucesivamente. Para la luz emitida por fuentes de luz de estado s\u00f3lido, no hay necesidad de ajustar los par\u00e1metros fotoel\u00e9ctricos pertinentes.la temperatura de la fuente de luz LED no debe exceder de 80 \u2103. A medida que aumenta la temperatura, la salida de luz y la esperanza de vida disminuye.relaci\u00f3n de salida de luz LED indica que la temperatura de uni\u00f3n LED a unos 50 \u2103, la relaci\u00f3n de salida de luz relativa de la l\u00e1mpara es 100%.<\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;Actualmente m\u00e1s com\u00fanmente utilizado fuente de luz del paquete: COB integrado, 2835, 3030, 3535, 5050, 5054, 7070, el uso de paquetes peque\u00f1os, primero y luego la cadena, fuente de luz de dise\u00f1o descentralizado, interfaz amigable, gran \u00e1rea de disipaci\u00f3n de calor, distribuci\u00f3n de calor, no se localiza el sobrecalentamiento, y mejorar efectivamente la vida de las l\u00e1mparas LED y linternas.<\/p>\n\n\n\n<p>L\u00e1mparas a prueba de explosiones LED a prueba de explosiones como una corriente principal de l\u00e1mparas a prueba de explosiones y linternas, en el campo a prueba de explosiones ha sido ampliamente utilizado. Sin embargo, todav\u00eda hay muchos problemas que necesitan ser resueltos utilizando las nuevas tecnolog\u00edas. Adem\u00e1s, el uso de l\u00e1mparas a prueba de explosiones LED a prueba de explosiones necesidad de reducir los costos, optimizar a\u00fan m\u00e1s el m\u00e9todo de disipaci\u00f3n de calor, elegir una fuente de alimentaci\u00f3n de accionamiento de corriente constante razonable, que es la clave para dise\u00f1ar una buena l\u00e1mpara a prueba de explosiones LED a prueba de explosiones.<\/p>","protected":false},"excerpt":{"rendered":"<p>LED explosion-proof lamps and lanterns design and manufacturing Electrical equipment used in explosive environments is divided into Class I, Class II and Class III. Class II and Class III non-mining LED explosion-proof lamps are mainly used in industries where flammable and explosive gases or dusts exist, such as petroleum, petrochemicals, chemicals, pharmaceuticals and so on. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[8,7],"tags":[],"class_list":["post-2232","post","type-post","status-publish","format-standard","hentry","category-explosion-proof-equipment","category-light"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/es\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"LED explosion-proof lamps and lanterns design and manufacturing Electrical equipment used in explosive environments is divided into Class I, Class II and Class III. Class II and Class III non-mining LED explosion-proof lamps are mainly used in industries where flammable and explosive gases or dusts exist, such as petroleum, petrochemicals, chemicals, pharmaceuticals and so on.&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/posts\/2232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/comments?post=2232"}],"version-history":[{"count":2,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/posts\/2232\/revisions"}],"predecessor-version":[{"id":2287,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/posts\/2232\/revisions\/2287"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/media?parent=2232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/categories?post=2232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/tags?post=2232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}