{"id":1880,"date":"2025-02-17T21:31:45","date_gmt":"2025-02-17T13:31:45","guid":{"rendered":"https:\/\/led.amasly.com\/?page_id=1880"},"modified":"2026-01-22T11:56:55","modified_gmt":"2026-01-22T03:56:55","slug":"metallurgical-industry-lighting-solution","status":"publish","type":"page","link":"https:\/\/led.amasly.com\/es\/solutions\/metallurgical-industry-lighting-solution\/","title":{"rendered":"Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-27bae773 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\">Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica Intro:<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">En los \u00faltimos a\u00f1os, la producci\u00f3n de las acer\u00edas ha atra\u00eddo cada vez m\u00e1s la atenci\u00f3n junto con el vigoroso desarrollo de la industria sider\u00fargica. Con la ampliaci\u00f3n de la escala de producci\u00f3n y la complicaci\u00f3n de los procesos de producci\u00f3n, la demanda de iluminaci\u00f3n en las acer\u00edas no ha dejado de crecer. Las zonas de fabricaci\u00f3n de hierro y acero requieren una gran luminosidad, con una iluminancia que debe alcanzar varios cientos de lux (Lx) o m\u00e1s. La zona de laminaci\u00f3n y las calles de las f\u00e1bricas, en cambio, hacen m\u00e1s hincapi\u00e9 en la uniformidad y estabilidad de la iluminancia, con requisitos que oscilan entre los 100Lx y los 200Lx. El sistema de iluminaci\u00f3n de las acer\u00edas consume una gran cantidad de energ\u00eda, pero adoptando tecnolog\u00edas de control inteligente como el PLC, puede conseguir un ajuste segmentado y autom\u00e1tico, reduciendo el consumo de energ\u00eda. Por lo tanto, las instalaciones de producci\u00f3n de las acer\u00edas no s\u00f3lo afectan a la eficiencia de la producci\u00f3n y el control de costes, sino que tambi\u00e9n influyen directamente en la calidad del producto, el consumo de energ\u00eda y la protecci\u00f3n del medio ambiente, por lo que son elementos clave indispensables en la industria sider\u00fargica. <\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-8cddf137 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/istockphoto-1069526610-612x612.webp.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/istockphoto-1069526610-612x612.webp.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/istockphoto-1069526610-612x612.webp.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/istockphoto-1069526610-612x612.webp.png\" alt=\"Metallurgical Industry lighting Solution\" class=\"uag-image-1882\" width=\"1012\" height=\"674\" title=\"Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Caracter\u00edsticas de la iluminaci\u00f3n de la industria metal\u00fargica Soluci\u00f3n<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">La iluminaci\u00f3n de las acer\u00edas tiene caracter\u00edsticas distintas, principalmente debido a los estrictos requisitos que deben cumplir los equipos de iluminaci\u00f3n. Dado el complejo entorno de producci\u00f3n de las acer\u00edas, los equipos de iluminaci\u00f3n deben poseer caracter\u00edsticas como ser a prueba de explosiones, resistentes a altas temperaturas, al agua y al polvo, para adaptarse a condiciones duras como las altas temperaturas, la humedad y el polvo. Adem\u00e1s, las acer\u00edas tienen unas exigencias extremadamente altas en cuanto a brillo y uniformidad de la iluminaci\u00f3n para garantizar que los trabajadores puedan identificar claramente los detalles durante las operaciones precisas y evitar riesgos para la seguridad. Los equipos de iluminaci\u00f3n LED, con sus ventajas de alta luminosidad, larga vida \u00fatil y ahorro de energ\u00eda, se han aplicado ampliamente en la iluminaci\u00f3n de acer\u00edas. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Adem\u00e1s, la iluminaci\u00f3n en las acer\u00edas tambi\u00e9n se centra en mejorar la eficiencia de la producci\u00f3n y garantizar la seguridad de los trabajadores. Un entorno de iluminaci\u00f3n de alta calidad no s\u00f3lo aumenta eficazmente la productividad de los trabajadores, sino que tambi\u00e9n reduce la incidencia de accidentes de seguridad. Mediante un dise\u00f1o razonable de la iluminaci\u00f3n, como el uso de luminarias LED de bajo consumo y la optimizaci\u00f3n de la disposici\u00f3n de la iluminaci\u00f3n, las acer\u00edas pueden garantizar la seguridad de la producci\u00f3n y, al mismo tiempo, alcanzar el objetivo de conservaci\u00f3n de energ\u00eda y reducci\u00f3n de emisiones. Por lo tanto, la iluminaci\u00f3n en las acer\u00edas no es s\u00f3lo una importante instalaci\u00f3n auxiliar en el proceso de producci\u00f3n, sino tambi\u00e9n un factor clave para mejorar la eficiencia de la producci\u00f3n, garantizar la seguridad de los trabajadores y lograr un desarrollo sostenible. <\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-05af630c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/ae0b20b76c613fca7f543c053045d0d3.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/ae0b20b76c613fca7f543c053045d0d3.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/ae0b20b76c613fca7f543c053045d0d3.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/ae0b20b76c613fca7f543c053045d0d3.png\" alt=\"\" class=\"uag-image-1883\" width=\"691\" height=\"436\" title=\"ae0b20b76c613fca7f543c053045d0d3\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica: Composici\u00f3n de los espacios de iluminaci\u00f3n en las acer\u00edas y requisitos de las especificaciones de iluminaci\u00f3n<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">El espacio de iluminaci\u00f3n de la planta sider\u00fargica se compone de m\u00faltiples componentes clave, como la iluminaci\u00f3n natural, la iluminaci\u00f3n artificial, el sistema de control inteligente de la iluminaci\u00f3n y el sistema de iluminaci\u00f3n de emergencia. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Iluminaci\u00f3n natural. La parte de iluminaci\u00f3n natural de la planta sider\u00fargica se basa principalmente en el dise\u00f1o de grandes ventanas y claraboyas para aprovechar al m\u00e1ximo la luz natural para la iluminaci\u00f3n. Las investigaciones demuestran que un dise\u00f1o de iluminaci\u00f3n natural bien planificado puede aumentar la iluminancia de la luz natural en los talleres de la planta sider\u00fargica hasta 500-1000 lx, reduciendo eficazmente el consumo de energ\u00eda de iluminaci\u00f3n artificial en 30%-40%, al tiempo que crea un entorno de trabajo luminoso y confortable para los empleados. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Iluminaci\u00f3n artificial. La iluminaci\u00f3n artificial en las acer\u00edas es de vital importancia. Suele emplear equipos de iluminaci\u00f3n de alta eficiencia, como l\u00e1mparas LED, que se disponen racionalmente en funci\u00f3n de las distintas necesidades de las \u00e1reas de producci\u00f3n para garantizar que la luminosidad de la iluminaci\u00f3n cumpla las normas prescritas. Por ejemplo, la iluminancia en la zona de fabricaci\u00f3n de acero no suele ser inferior a 300 lx, mientras que en la zona de laminaci\u00f3n de acero debe alcanzar m\u00e1s de 500 lx. En comparaci\u00f3n con los m\u00e9todos de iluminaci\u00f3n tradicionales, el consumo total de energ\u00eda se reduce entre 201 y 301 TTP3T, lo que mejora eficazmente la eficiencia de la producci\u00f3n y la tasa de utilizaci\u00f3n de la energ\u00eda de la acer\u00eda. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">El sistema inteligente de control de la iluminaci\u00f3n El sistema de control inteligente de la iluminaci\u00f3n de la planta sider\u00fargica integra tecnolog\u00eda inform\u00e1tica, tecnolog\u00eda de comunicaci\u00f3n en red y tecnolog\u00eda de control autom\u00e1tico, logrando una gesti\u00f3n refinada y un ajuste autom\u00e1tico de los equipos de iluminaci\u00f3n. Se estima que despu\u00e9s de la adopci\u00f3n de este sistema, el consumo de energ\u00eda de iluminaci\u00f3n de la planta de acero se puede reducir en m\u00e1s de 30%, al tiempo que mejora la calidad de la iluminaci\u00f3n y la eficiencia de la producci\u00f3n, trayendo importantes beneficios de ahorro de energ\u00eda y beneficios econ\u00f3micos para la planta de acero. Sistema de iluminaci\u00f3n de emergencia. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">El sistema de iluminaci\u00f3n de emergencia de la acer\u00eda tambi\u00e9n es muy importante. Puede ponerse en marcha r\u00e1pidamente cuando falla el suministro el\u00e9ctrico principal, proporcionando a los trabajadores rutas de evacuaci\u00f3n claras y la iluminaci\u00f3n necesaria para garantizar la evacuaci\u00f3n segura del personal. Seg\u00fan las normas pertinentes, la iluminancia de los dispositivos de iluminaci\u00f3n de emergencia no suele ser inferior a 10% de la iluminancia de la iluminaci\u00f3n normal, y el sistema de iluminaci\u00f3n de emergencia debe garantizar una iluminaci\u00f3n continua durante al menos 30 minutos despu\u00e9s de un corte de energ\u00eda. En algunas \u00e1reas clave, como la sala de control principal y la sala de despacho, el sistema de iluminaci\u00f3n de emergencia debe incluso garantizar el funcionamiento continuo durante m\u00e1s de 3 horas despu\u00e9s de un corte de energ\u00eda, proporcionando una s\u00f3lida garant\u00eda para la producci\u00f3n segura de la planta sider\u00fargica. <\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-6d107573 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/58245100029892c26dd98a745b8d78df.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/58245100029892c26dd98a745b8d78df.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/58245100029892c26dd98a745b8d78df.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/58245100029892c26dd98a745b8d78df.png\" alt=\"\" class=\"uag-image-1884\" width=\"689\" height=\"791\" title=\"58245100029892c26dd98a745b8d78df\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica: Requisitos de las normas de iluminaci\u00f3n<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">Las plantas sider\u00fargicas se dividen funcionalmente en \u00e1reas como procesamiento de materias primas, fabricaci\u00f3n de hierro, fabricaci\u00f3n de acero, laminaci\u00f3n de acero e instalaciones auxiliares. En consonancia con los distintos dise\u00f1os espaciales de estas \u00e1reas, los entornos de iluminaci\u00f3n tambi\u00e9n difieren. La zona de procesamiento de materias primas suele estar equipada con iluminaci\u00f3n de alta intensidad, con una iluminancia superior a 500 lux. La iluminaci\u00f3n alrededor de los altos hornos y las estufas de chorro caliente en la zona de fabricaci\u00f3n de hierro debe tener una iluminancia no inferior a 300 lux. En los equipos clave de la siderurgia, como los convertidores y los hornos el\u00e9ctricos, la iluminancia debe alcanzar entre 500 y 1.000 lux. En la zona de laminaci\u00f3n, debido a la densidad de los equipos y a la complejidad de los procesos, la iluminancia no suele ser inferior a 750 lux. La iluminaci\u00f3n de las zonas de instalaciones auxiliares, como las de suministro el\u00e9ctrico y tratamiento de aguas, se dise\u00f1a en funci\u00f3n de requisitos espec\u00edficos. <\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica:El taller metal\u00fargico es un lugar con requisitos especiales, y los requisitos para los accesorios de iluminaci\u00f3n tambi\u00e9n son muy altos. Los siguientes son los requisitos para los accesorios de iluminaci\u00f3n en el taller metal\u00fargico:<\/h3>\n\n\n\n<p class=\"has-medium-font-size\">1. Rendimiento a prueba de explosiones: El taller metal\u00fargico es un lugar donde se generan f\u00e1cilmente gases explosivos, por lo que las luminarias deben tener un rendimiento a prueba de explosiones y ser capaces de soportar el impacto de gases explosivos. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">2. Alta eficiencia luminosa: El taller metal\u00fargico requiere efectos de iluminaci\u00f3n de alto brillo y alta definici\u00f3n, por lo que las luminarias deben tener una alta eficiencia luminosa y ser capaces de proporcionar suficiente iluminancia y brillo. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">3. Resistencia al calor: La temperatura ambiente en el taller metal\u00fargico es relativamente alta, por lo que las luminarias deben ser resistentes al calor y no da\u00f1arse f\u00e1cilmente. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">4. Impermeable y a prueba de polvo: El entorno en el taller metal\u00fargico es relativamente duro, por lo que los accesorios de iluminaci\u00f3n deben tener funciones a prueba de agua y polvo para garantizar su vida \u00fatil y la seguridad. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">5. Larga vida \u00fatil: Las luminarias del taller metal\u00fargico deben tener una larga vida \u00fatil, poder funcionar de forma estable durante mucho tiempo y reducir la frecuencia de mantenimiento y sustituci\u00f3n. <\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Para los requisitos especiales de los talleres metal\u00fargicos, pueden adoptarse las siguientes soluciones de iluminaci\u00f3n antideflagrante: <\/h3>\n\n\n\n<p class=\"has-medium-font-size\">1. Seleccione aparatos de iluminaci\u00f3n que cumplan los requisitos antideflagrantes, como los de tipo antideflagrante y de seguridad aumentada, que puedan resistir el impacto de gases explosivos. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">2. Utilice aparatos de iluminaci\u00f3n LED de alta eficiencia que proporcionen suficiente iluminaci\u00f3n y brillo, con un bajo consumo de energ\u00eda y una larga vida \u00fatil. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">3. Optimizar el dise\u00f1o de disipaci\u00f3n de calor de las luminarias para garantizar un funcionamiento estable en entornos de alta temperatura. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">4. Utilice carcasas de l\u00e1mparas estancas al agua y al polvo para soportar las duras condiciones de los talleres metal\u00fargicos. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">5. Disponer razonablemente las posiciones y cantidades de los aparatos de alumbrado para garantizar efectos luminosos uniformes y adecuados. <\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-523d2e6e wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/istockphoto-495203448-612x612.webp.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/istockphoto-495203448-612x612.webp.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/istockphoto-495203448-612x612.webp.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/02\/istockphoto-495203448-612x612.webp.png\" alt=\"\" class=\"uag-image-1886\" width=\"1012\" height=\"674\" title=\"istockphoto-495203448-612x612.webp\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica: Estrategias inteligentes de control del alumbrado para acer\u00edas<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica:  Simplificar el dise\u00f1o de la escena.<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">Muchos dise\u00f1adores caen a menudo en la \"trampa\" de la tecnificaci\u00f3n excesiva, es decir, no deben centrarse \u00fanicamente en demostrar la complejidad t\u00e9cnica descuidando los requisitos de iluminaci\u00f3n y las experiencias en entornos de producci\u00f3n reales. En el dise\u00f1o de estrategias inteligentes de control de la iluminaci\u00f3n para plantas sider\u00fargicas, debe evitarse la tecnificaci\u00f3n excesiva. Hay que prestar atenci\u00f3n a las necesidades reales de iluminaci\u00f3n y a las experiencias operativas de los empleados. El dise\u00f1o debe buscar la simplicidad. Se recomienda que cada acci\u00f3n de control de escenas de iluminaci\u00f3n no exceda de cinco, y el n\u00famero de activadores de condiciones debe reducirse para garantizar la estabilidad y fiabilidad del control de la iluminaci\u00f3n, y para reducir la tasa de fallos y los costes de operaci\u00f3n y mantenimiento. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">En el control inteligente de la iluminaci\u00f3n de las plantas sider\u00fargicas, deben tomarse como gu\u00eda las necesidades reales. Por ejemplo, en el \u00e1rea de fabricaci\u00f3n de acero, el brillo de la iluminaci\u00f3n y la temperatura de color pueden ajustarse autom\u00e1ticamente en funci\u00f3n del estado de funcionamiento del horno de fabricaci\u00f3n de acero y, al mismo tiempo, puede regularse autom\u00e1ticamente en funci\u00f3n de la intensidad de la luz natural. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">Brillo de la iluminaci\u00f3n. Este dise\u00f1o no s\u00f3lo cumple los requisitos de producci\u00f3n, sino que tambi\u00e9n simplifica la complejidad del control, mejora la experiencia operativa de los empleados y consigue estabilidad, fiabilidad y facilidad de uso en el control de la iluminaci\u00f3n. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">El modo de control suele constar de tres partes: sistema de control distribuido, controlador l\u00f3gico programable e interfaz hombre-m\u00e1quina. <\/p>\n\n\n\n<p class=\"has-medium-font-size\">La estrategia de control inteligente del alumbrado de las acer\u00edas se basa en tres componentes: sistemas de control distribuido, controladores l\u00f3gicos programables e interfaces hombre-m\u00e1quina. Los sensores perciben la informaci\u00f3n ambiental de la f\u00e1brica, como la luz, la temperatura y la humedad; los controladores reciben los datos y hacen juicios l\u00f3gicos, para luego emitir instrucciones de control; los actuadores ajustan el brillo y la temperatura de color de las luces de acuerdo con las instrucciones. Los tres trabajan juntos para lograr un control preciso y eficaz de la iluminaci\u00f3n, mejorar la eficiencia de la producci\u00f3n, reducir el consumo de energ\u00eda y crear un entorno de producci\u00f3n confortable y que ahorre energ\u00eda. <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-large-font-size\">Soluci\u00f3n de iluminaci\u00f3n para la industria metal\u00fargica:  Productos de uso com\u00fan para el control inteligente de la iluminaci\u00f3n en acer\u00edas<\/h2>\n\n\n\n<p class=\"has-medium-font-size\">Los productos m\u00e1s comunes para el control inteligente de la iluminaci\u00f3n en las plantas sider\u00fargicas incluyen tipos de sensores (sensores de luz, sensores del cuerpo humano, sensores de temperatura y humedad, etc.), tipos de controladores y actuadores (controladores inteligentes de iluminaci\u00f3n, m\u00f3dulos de regulaci\u00f3n, dispositivos de gesti\u00f3n de energ\u00eda, cajas de distribuci\u00f3n a prueba de explosiones, etc.), tipos de equipos de iluminaci\u00f3n (l\u00e1mparas inteligentes LED, l\u00e1mparas a prueba de explosiones, etc.) y tipos de equipos de comunicaci\u00f3n de red y gesti\u00f3n inteligente (dispositivos de comunicaci\u00f3n de red, sistemas de gesti\u00f3n inteligente, etc.).<\/p>\n\n\n\n<p>Est\u00e1ndar: <a href=\"http:\/\/www.iec.com\" rel=\"nofollow noopener\" target=\"_blank\">IEC 60598<\/a><\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c7d898dd alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Productos relacionados<\/h2>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-66e4defc alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a42945f9\">\n<div class=\"wp-block-uagb-image uagb-block-7296296b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png\" alt=\"\" class=\"uag-image-1495\" width=\"300\" height=\"300\" title=\"Luces de gran altura a prueba de explosiones\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4d3efde5\">\n<div class=\"wp-block-uagb-image uagb-block-c9e90797 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png\" alt=\"\" class=\"uag-image-1132\" width=\"300\" height=\"300\" title=\"Luces LED-tri-proof2\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-11c2578b\">\n<div class=\"wp-block-uagb-image uagb-block-6e8883aa wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png\" alt=\"\" class=\"uag-image-1501\" width=\"300\" height=\"300\" title=\"L\u00e1mpara LED antideflagrante para gasolineras\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-548945b5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-967755d5\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/\">Luces LED antideflagrantes<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9bc52fc2\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/\">Luces LED Tri-Proof<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8ffa0a23\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/\">Luces de gasolinera a prueba de explosiones<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-29499fe0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-777ee1c7\">\n<div class=\"wp-block-uagb-image uagb-block-2e9a1851 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg\" alt=\"\" class=\"uag-image-1526\" width=\"300\" height=\"300\" title=\"L\u00e1mpara de inundaci\u00f3n LED 50W 100W 150W 200W 300W\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-af8c8683\">\n<div class=\"wp-block-uagb-image uagb-block-67947854 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png\" alt=\"\" class=\"uag-image-1130\" width=\"300\" height=\"300\" title=\"luz led-tri-proof\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0fdfdd58\">\n<div class=\"wp-block-uagb-image uagb-block-1187d32d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg\" alt=\"\" class=\"uag-image-1145\" width=\"300\" height=\"300\" title=\"Alumbrado p\u00fablico LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6a60882c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-f1e91a35\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/\">Proyectores LED<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-165bfa58\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/\">Tubos de luz LED trif\u00e1sicos<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f6096e3b\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/\">Alumbrado p\u00fablico LED<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Metallurgical Industry lighting Solution Metallurgical Industry Lighting Solution Introduce: In recent years, the production of steel mills has increasingly drawn attention along with the vigorous development of the steel industry. With the expansion of production scale and the complication of production processes, the demand for lighting in steel mills has been constantly growing. The ironmaking [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1808,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1880","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/es\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"Metallurgical Industry lighting Solution Metallurgical Industry Lighting Solution Introduce: In recent years, the production of steel mills has increasingly drawn attention along with the vigorous development of the steel industry. With the expansion of production scale and the complication of production processes, the demand for lighting in steel mills has been constantly growing. The ironmaking&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages\/1880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/comments?post=1880"}],"version-history":[{"count":5,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages\/1880\/revisions"}],"predecessor-version":[{"id":4574,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages\/1880\/revisions\/4574"}],"up":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages\/1808"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/media?parent=1880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}