{"id":1170,"date":"2024-07-16T18:03:33","date_gmt":"2024-07-16T10:03:33","guid":{"rendered":"https:\/\/led.amasly.com\/?page_id=1170"},"modified":"2026-01-18T20:32:03","modified_gmt":"2026-01-18T12:32:03","slug":"led-tri-proof-light-2","status":"publish","type":"page","link":"https:\/\/led.amasly.com\/es\/products\/led-tri-proof-light-2\/","title":{"rendered":"Luz Tri-Proof"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e407eb08 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-7c0a134c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">Luz LED Tri-Proof<\/h1>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Definici\u00f3n y uso de luz trif\u00e1sica<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Definici\u00f3n: Las luces trif\u00e1sicas son conocidas por sus funciones impermeables, antipolvo y anticorrosi\u00f3n.<\/li>\n\n\n\n<li>Usos: Principalmente utilizado en plantas industriales, almacenes, salas de m\u00e1quinas, laboratorios, talleres y otros polvorientos, vapor de agua y puede tener sustancias corrosivas en el ambiente \u00e1spero.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Caracter\u00edsticas t\u00e9cnicas de la luz Tri-proof<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Nivel de protecci\u00f3n: normalmente hasta IP65 o superior, puede evitar eficazmente la entrada de polvo y el impacto de agua pulverizada a baja presi\u00f3n.<\/li>\n\n\n\n<li>Materiales y tratamiento superficial: se utilizan materiales resistentes a la corrosi\u00f3n y un tratamiento superficial especial para adaptarse al entorno corrosivo.<\/li>\n\n\n\n<li>Rango de temperatura de funcionamiento: generalmente entre -20 \u2103 y +50 \u2103, para adaptarse a los cambios de temperatura ambientales convencionales.<\/li>\n\n\n\n<li>Fuente de luz: en su mayor\u00eda adopta LED, alta eficiencia luminosa, generalmente hasta 100 lm\/W o m\u00e1s.<\/li>\n\n\n\n<li>Modo de control: puede tener sistema de control inteligente, como interruptor de inducci\u00f3n y funci\u00f3n de atenuaci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Escena de aplicaci\u00f3n de luz trif\u00e1sica<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Preste m\u00e1s atenci\u00f3n al rendimiento de protecci\u00f3n, adecuado para un funcionamiento estable a largo plazo y el duro entorno del lugar. Tales como plantas qu\u00edmicas, centrales el\u00e9ctricas, plantas de hierro y acero, plantas petroqu\u00edmicas, barcos, salas de exposiciones, aparcamientos subterr\u00e1neos y as\u00ed sucesivamente.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Mantenimiento y conservaci\u00f3n de la luz Tri-proof<\/strong><\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Compruebe peri\u00f3dicamente el aspecto de las l\u00e1mparas y limpie el polvo y la suciedad.<\/li>\n\n\n\n<li>Compruebe el rendimiento de sellado y el sistema de control inteligente.<\/li>\n\n\n\n<li>Seg\u00fan el entorno y la frecuencia de uso, realice el mantenimiento y la conservaci\u00f3n necesarios.<\/li>\n<\/ol>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6f08c8e4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-b229cb92\">\n<h3 class=\"wp-block-heading\">Contenido<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-container-core-buttons-is-layout-45b20515 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es\/products\/explosion-proof-lights\/\">Luces antideflagrantes<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es\/products\/ex-proof-electrical-appliance\/\">Aparato el\u00e9ctrico a prueba de explosiones<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es\/products\/led-tri-proof-light-2\/\">Luz LED a prueba de tropiezos<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es\/products\/led-high-bay-light\/\">Luz LED para techos altos<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es\/products\/led-flood-lights\/\">Proyectores LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es\/products\/led-street-lights\/\">Farolas LED<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/led.amasly.com\/es\/products\/solar-lights\/\">Luz solar LED<\/a><\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><\/h4>\n\n\n\n<h4 class=\"wp-block-heading\">P\u00f3ngase en contacto con<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Correo electr\u00f3nico: sales01@amasly.com      <\/li>\n\n\n\n<li>M\u00f3vil: +86 13732643699                    <\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6c5ab58c\">\n<div class=\"wp-block-uagb-image uagb-block-14a4df1b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/led-tri-proof-light.png\" alt=\"\" class=\"uag-image-1130\" width=\"299\" height=\"303\" title=\"luz led-tri-proof\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<p>A<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-d44a74cf\">\n<div class=\"wp-block-uagb-image uagb-block-61a2029c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-tri-proof-lights2.png\" alt=\"Tri-Proof Light\" class=\"uag-image-1132\" width=\"299\" height=\"303\" title=\"Luces LED-tri-proof2\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n\n\n\n<p>B<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ceb98619\">\n<div class=\"wp-block-uagb-image uagb-block-c5026e55 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/Explosion-proof-linear-fluorescence-lights.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/Explosion-proof-linear-fluorescence-lights.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/Explosion-proof-linear-fluorescence-lights.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/Explosion-proof-linear-fluorescence-lights.png\" alt=\"\" class=\"uag-image-1122\" width=\"299\" height=\"303\" title=\"L\u00e1mparas de fluorescencia lineal antideflagrantes\" loading=\"lazy\" role=\"img\"><\/figure><\/div>\n\n\n\n<p>C<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Luz LED Amasly <\/strong><strong>PREGUNTAS FRECUENTES<\/strong><strong><\/strong><\/h2>\n\n\n\n<p><strong>P1.\u00bfPuedo recibir un pedido de muestra de luz led?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: S\u00ed, aceptamos pedidos de muestras para probar y comprobar la calidad. Las muestras mezcladas son aceptables.<\/p>\n\n\n\n<p><strong>P2: \u00bfY el plazo de entrega?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: La muestra necesita 3-5 d\u00edas, el tiempo de producci\u00f3n en masa necesita 1-2 semanas.<\/p>\n\n\n\n<p><strong>Q3.Do usted tiene cualquier l\u00edmite MOQ para la luz led orden?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: Bajo MOQ 1pc para la comprobaci\u00f3n de la muestra est\u00e1 disponible.<\/p>\n\n\n\n<p><strong>Q4. \u00bfC\u00f3mo env\u00edan la mercanc\u00eda y cu\u00e1nto tarda en llegar?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: Normalmente enviamos por DHL, UPS, FedEx o TNT. Por lo general tarda 3-5 d\u00edas en llegar. L\u00ednea a\u00e9rea y env\u00edo del mar tambi\u00e9n opcional.<\/p>\n\n\n\n<p><strong>Q5. \u00bfC\u00f3mo tramitar un pedido de luz led?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>A:<\/p>\n\n\n\n<p>En primer lugar, comun\u00edquenos sus necesidades o su solicitud.<\/p>\n\n\n\n<p>En segundo lugar, presupuestamos seg\u00fan sus requisitos o nuestras sugerencias.<\/p>\n\n\n\n<p>En tercer lugar, el cliente confirma las muestras y realiza el dep\u00f3sito para el pedido formal.<\/p>\n\n\n\n<p>En cuarto lugar, organizamos la producci\u00f3n.<\/p>\n\n\n\n<p><strong>P6.\u00bfPuedo imprimir mi <\/strong><strong>LOGO<\/strong><strong>&nbsp;en producto de luz led ?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: S\u00ed, por favor inf\u00f3rmenos formalmente antes de nuestra producci\u00f3n y confirmar el dise\u00f1o en primer lugar sobre la base de nuestra muestra.<\/p>\n\n\n\n<p><strong>P7: \u00bfOfrecen garant\u00eda para los productos?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>R: S\u00ed, ofrecemos de 2 a 5 a\u00f1os de garant\u00eda para nuestros productos.<\/p>\n\n\n\n<p><strong>P8: \u00bfC\u00f3mo tratar los fallos?<\/strong><strong><\/strong><\/p>\n\n\n\n<p>A:<\/p>\n\n\n\n<p>En primer lugar, nuestros productos se producen dinstrict sistema de control de calidad y la tasa de defectos ser\u00e1 inferior a 0,2%<\/p>\n\n\n\n<p>En segundo lugar, durante el per\u00edodo de garant\u00eda, proporcionaremos piezas para sustituir la pieza defectuosa.. Para los pedidos al por mayor, proporcionaremos piezas vulnerables por adelantado, o podemos discutir soluciones, incluyendo la retirada del producto, en funci\u00f3n de la situaci\u00f3n real.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Productos relacionados<\/h2>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-66e4defc alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-a42945f9\">\n<div class=\"wp-block-uagb-image uagb-block-7296296b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/explosion-proof-lights\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/Explosion-proof-high-bay-lights.png\" alt=\"\" class=\"uag-image-1495\" width=\"300\" height=\"300\" title=\"Luces de gran altura a prueba de explosiones\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4d3efde5\">\n<div class=\"wp-block-uagb-image uagb-block-c9e90797 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/ex-proof-electrical-appliance\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/01\/Explosion-proof-axial-flow-fan.jpg\" alt=\"Ex-Proof Electrical Appliance\" class=\"uag-image-1767\" width=\"300\" height=\"300\" title=\"Ventilador axial antideflagrante\" loading=\"lazy\" role=\"img\"\/><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-11c2578b\">\n<div class=\"wp-block-uagb-image uagb-block-6e8883aa wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/explosion-proof-lights\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/09\/LED-Explosion-Proof-Gas-Station-Light.png\" alt=\"\" class=\"uag-image-1501\" width=\"300\" height=\"300\" title=\"L\u00e1mpara LED antideflagrante para gasolineras\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-548945b5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-967755d5\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/explosion-proof-lights\/\">Luces LED antideflagrantes<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9bc52fc2\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/ex-proof-electrical-appliance\/\">Aparato el\u00e9ctrico Ex-Proof<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8ffa0a23\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/explosion-proof-lights\/\">Luces de gasolinera a prueba de explosiones<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-29499fe0 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-777ee1c7\">\n<div class=\"wp-block-uagb-image uagb-block-2e9a1851 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/led-flood-lights\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/10\/50W-100W-150W-200W-300W-LED-Flood-Light.jpg\" alt=\"\" class=\"uag-image-1526\" width=\"300\" height=\"300\" title=\"L\u00e1mpara de inundaci\u00f3n LED 50W 100W 150W 200W 300W\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-af8c8683\">\n<div class=\"wp-block-uagb-image uagb-block-67947854 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/led-high-bay-light\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp ,https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2025\/05\/high-bay-light.webp\" alt=\"\" class=\"uag-image-3954\" width=\"300\" height=\"300\" title=\"luz de gran altura\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0fdfdd58\">\n<div class=\"wp-block-uagb-image uagb-block-1187d32d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><a class=\"\" href=\"https:\/\/led.amasly.com\/es\/products\/\" target=\"\" rel=\"noopener\"><img decoding=\"async\" srcset=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg ,https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 780w, https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/led.amasly.com\/wp-content\/uploads\/2024\/07\/LED-street-light.jpg\" alt=\"\" class=\"uag-image-1145\" width=\"300\" height=\"300\" title=\"Alumbrado p\u00fablico LED\" loading=\"lazy\" role=\"img\"><\/a><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-6a60882c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-f1e91a35\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/led-flood-lights\/\">Proyectores LED<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-165bfa58\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/led-high-bay-light\/\">Luces LED High Bay<\/a><\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f6096e3b\">\n<h4 class=\"wp-block-heading has-text-align-center\"><a href=\"https:\/\/led.amasly.com\/es\/products\/https:\/\/led.amasly.com\/products\/led-street-lights\/\">Alumbrado p\u00fablico LED<\/a><\/h4>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-99c0e0a5 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>LED Tri-Proof Light Definition and Usage of Tri-proof Light Tri-proof\u00a0light technical characteristics Tri-proof light application scene Tri-proof light maintenance and maintenance Content Contact A B C Amasly LED Light FAQ Q1.Can I have a sample order for led light ? A: Yes, we welcome sample order to test and check quality. Mixed samples are acceptable. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1039,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"enabled","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":"[]"},"class_list":["post-1170","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Joe","author_link":"https:\/\/led.amasly.com\/es\/author\/jacklin\/"},"uagb_comment_info":0,"uagb_excerpt":"LED Tri-Proof Light Definition and Usage of Tri-proof Light Tri-proof\u00a0light technical characteristics Tri-proof light application scene Tri-proof light maintenance and maintenance Content Contact A B C Amasly LED Light FAQ Q1.Can I have a sample order for led light ? A: Yes, we welcome sample order to test and check quality. Mixed samples are acceptable.&hellip;","_links":{"self":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages\/1170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/comments?post=1170"}],"version-history":[{"count":10,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages\/1170\/revisions"}],"predecessor-version":[{"id":4538,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages\/1170\/revisions\/4538"}],"up":[{"embeddable":true,"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/pages\/1039"}],"wp:attachment":[{"href":"https:\/\/led.amasly.com\/es\/wp-json\/wp\/v2\/media?parent=1170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}